{"id":7234,"date":"2018-02-19T11:47:40","date_gmt":"2018-02-19T14:47:40","guid":{"rendered":"https:\/\/prodoctor.net\/blog\/?p=7234"},"modified":"2019-04-01T10:57:33","modified_gmt":"2019-04-01T13:57:33","slug":"melhorar-atendimento-telefonico-de-clinicas-consultorios","status":"publish","type":"post","link":"https:\/\/prodoctor.net\/blog\/melhorar-atendimento-telefonico-de-clinicas-consultorios\/","title":{"rendered":"Como melhorar o atendimento telef\u00f4nico de cl\u00ednicas e consult\u00f3rios"},"content":{"rendered":"<p>Responsabilidade, educa\u00e7\u00e3o e paci\u00eancia s\u00e3o algumas das exig\u00eancias de como melhorar o atendimento telef\u00f4nico do seu local de trabalho. Elas s\u00e3o\u00a0<strong>essenciais<\/strong> para quem for trabalhar com <strong>atendimento<\/strong>. O <strong>treinamento<\/strong> das empresas para quem exerce a fun\u00e7\u00e3o \u00e9 <strong>imprescind\u00edvel<\/strong> e deve ser realizado periodicamente.<\/p>\n<p>O atendimento telef\u00f4nico \u00e9 um <strong>ponto estrat\u00e9gico<\/strong> e de <strong>import\u00e2ncia vital<\/strong> para as cl\u00ednicas\/consult\u00f3rios no marketing m\u00e9dico. Voc\u00ea deve estar atento para isto, pois \u00e9 preciso ressaltar que ali pode estar acontecendo o <strong>primeiro contato do paciente<\/strong> com o seu estabelecimento. \u00c9 necess\u00e1rio, ent\u00e3o, dispensar <strong>aten\u00e7\u00e3o especial <\/strong>para este setor, a fim de responder de forma eficaz a todas as demandas.<\/p>\n<p>Sabe-se que muitas pessoas j\u00e1 carregam na mente uma <strong>impress\u00e3o negativa<\/strong> dos atendimentos telef\u00f4nicos. Assim, seus colaboradores devem estar devidamente <strong>treinados e motivados<\/strong> para exercer a tarefa.<\/p>\n<p>\u00c9 fundamental que cada um tenha <strong>consci\u00eancia da import\u00e2ncia<\/strong> que representa para a empresa, pois \u00e9 uma das pe\u00e7as fundamentais de toda a engrenagem.<\/p>\n<p>Confira, a seguir, algumas <strong>dicas<\/strong> para <strong>melhorar o atendimento telef\u00f4nico<\/strong> de sua cl\u00ednica\/consult\u00f3rio:<\/p>\n<h3>Dicas para melhorar o atendimento telef\u00f4nico de sua cl\u00ednica\/consult\u00f3rio<\/h3>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-7240\" src=\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2018\/02\/atendimento-telefone-clinica-consultorio.jpg\" alt=\"Dicas para melhorar o atendimento telef\u00f4nico de sua cl\u00ednica\/consult\u00f3rio\" width=\"770\" height=\"250\" srcset=\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2018\/02\/atendimento-telefone-clinica-consultorio.jpg 770w, https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2018\/02\/atendimento-telefone-clinica-consultorio-300x97.jpg 300w, https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2018\/02\/atendimento-telefone-clinica-consultorio-768x249.jpg 768w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/p>\n<h4>1 &#8211; Tenha uma boa secret\u00e1ria<\/h4>\n<p>Al\u00e9m de <strong>recepcionar os pacientes pessoalmente<\/strong>, \u00e9 ela quem ir\u00e1 ligar e receber as liga\u00e7\u00f5es. Encontrar as <strong>pessoas certas<\/strong> para exercer essa fun\u00e7\u00e3o nas <strong>cl\u00ednicas e nos consult\u00f3rios<\/strong> \u00e9 de <strong>grande import\u00e2ncia<\/strong>. Veja <a href=\"https:\/\/prodoctor.net\/blog\/2016\/01\/9-dicas-para-contratar-uma-boa-secretaria\/\" target=\"_blank\" rel=\"noopener noreferrer\">9 dicas para contratar uma boa secret\u00e1ria<\/a>.<\/p>\n<h4>2 &#8211; Defina um roteiro<\/h4>\n<p>Em sua <strong>cl\u00ednica\/consult\u00f3rio<\/strong>, todas as a\u00e7\u00f5es devem <strong>seguir um roteiro pr\u00e9-determinado.<\/strong>\u00a0Isso ajudar\u00e1\u00a0a cumprir as tarefas \u00e0 risca, <strong>evitando contratempos<\/strong> e a interrup\u00e7\u00e3o do fluxo de trabalho.<\/p>\n<p>Embora siga o roteiro, o (a) atendente deve ter consci\u00eancia que est\u00e1 <strong>tratando com pessoas. <\/strong>Ele(a)\u00a0deve se atentar para que o relacionamento seja sempre o <strong>mais humano poss\u00edvel<\/strong>. As pessoas n\u00e3o gostam de se sentir tratadas como m\u00e1quinas.<\/p>\n<h4>3 &#8211; Chame o paciente pelo nome e fa\u00e7a a pron\u00fancia do mesmo corretamente<\/h4>\n<p>Certamente faz parte de qualquer regra de conviv\u00eancia, principalmente em se tratando do relacionamento entre uma empresa com seus clientes. E sua cl\u00ednica\/consult\u00f3rio \u00e9 um empreendimento que precisa sobreviver em um <strong>mercado cada vez mais concorrido<\/strong>.<\/p>\n<p>Fa\u00e7a do respeito tamb\u00e9m um diferencial. <strong>Chame seu paciente sempre pelo nome<\/strong>, procurando saber a pron\u00fancia correta em caso de dificuldade.<\/p>\n<p>Isto demonstra respeito e apre\u00e7o, criando desde cedo uma empatia que poder\u00e1 ser ampliada ao longo do tempo e das consultas, fortalecendo os la\u00e7os e fidelizando os clientes.<\/p>\n<h4>4 &#8211; Seja sempre educado e atencioso<\/h4>\n<p>\u00c9 o passo inicial do trabalho, com o profissional atendendo com a <strong>melhor voz<\/strong>, de maneira firme, mas em <strong>tom cordial e atencioso<\/strong>.<\/p>\n<p>As liga\u00e7\u00f5es devem ser recebidas com os tradicionais <strong>\u201cbom dia\u201d, \u201cboa tarde\u201d e \u201cboa noite\u201d<\/strong>, ap\u00f3s declinar o nome da cl\u00ednica\/consult\u00f3rio. Desta forma, o\u00a0treinamento peri\u00f3dico e a experi\u00eancia di\u00e1ria fortalecer\u00e3o a <strong>qualidade do atendimento<\/strong>.<\/p>\n<p>Coloque-se \u00e0 <strong>disposi\u00e7\u00e3o<\/strong> para dar as informa\u00e7\u00f5es requisitadas e seja <strong>objetivo. <\/strong>\u00c9 preciso ouvir o paciente com <strong>calma<\/strong> e <strong>tranquilidade,<\/strong> antes de se despedir, pergunte se o interlocutor gostaria de falar algo mais e se existe alguma d\u00favida.<\/p>\n<h4>5 &#8211; Tenha aten\u00e7\u00e3o com os dados do paciente<\/h4>\n<p>\u00c9 importante ter total <strong>aten\u00e7\u00e3o durante a conversa<\/strong>. Al\u00e9m de passar para o paciente respeito, a concentra\u00e7\u00e3o \u00e9 fundamental para o desenrolar do di\u00e1logo.<\/p>\n<p><strong>Confirme todas as informa\u00e7\u00f5es<\/strong>, como por exemplo, dados do paciente, endere\u00e7o, telefone para contato, conv\u00eanio, nome do m\u00e9dico, dia e hora da consulta.<\/p>\n<h4>6 &#8211; Tenha paci\u00eancia<\/h4>\n<p>Se o paciente <strong>ligou para reclamar<\/strong>, ou\u00e7a com aten\u00e7\u00e3o, esperando a pessoa se acalmar e dizendo que est\u00e1 ali para <strong>ajud\u00e1-lo a solucionar o problema<\/strong> da melhor forma.<\/p>\n<p><strong>N\u00e3o altere a voz e nem discuta<\/strong> com o interlocutor, lembrando a m\u00e1xima de que <em>\u201co cliente sempre tem raz\u00e3o\u201d<\/em>. Se a pessoa quer e insiste em falar com o m\u00e9dico, explique, com calma e educadamente, que assim que for poss\u00edvel ele <strong>retornar\u00e1 a liga\u00e7\u00e3o<\/strong>, pois naquele momento o consult\u00f3rio\/cl\u00ednica est\u00e1 muito cheio, por exemplo.<\/p>\n<p>Assegure a ele que o <strong>seu recado ser\u00e1 transmitido<\/strong>. Anote tudo e releia para a pessoa, para que ela se <strong>tranquilize<\/strong>.<\/p>\n<h4>7 &#8211; N\u00e3o ocupe a linha telef\u00f4nica desnecessariamente<\/h4>\n<p>Algo que <strong>incomoda<\/strong> qualquer paciente \u00e9 tentar contato com a cl\u00ednica\/consult\u00f3rio e a <strong>linha estar sempre ocupada<\/strong>.<\/p>\n<p>Se perceber que a demanda de liga\u00e7\u00f5es est\u00e1 alta, contrate uma <strong>linha extra e outra atendente.<\/strong>\u00a0Outra op\u00e7\u00e3o \u00e9 recorrer a outro meio de contato, como os <strong>aplicativos de mensagens instant\u00e2neas<\/strong>. Assim, voc\u00ea ir\u00e1\u00a0<strong>facilitar<\/strong> ao m\u00e1ximo o contato do paciente.<\/p>\n<p>Caso de algum <strong>atendimento se estenda<\/strong>, pe\u00e7a ao interlocutor para <strong>aguardar alguns instantes<\/strong>. Seja cordial e, em caso de haver demora, explique o motivo e solicite o n\u00famero do paciente para que possa retornar a liga\u00e7\u00e3o logo em seguida. E <strong>cumpra o prometido<\/strong>, telefonando assim que estiver liberada.<\/p>\n<p>Isto \u00e9 demonstra\u00e7\u00e3o de respeito, que reverter\u00e1 em aumento no <strong>grau de confian\u00e7a<\/strong> dos pacientes para com a cl\u00ednica\/consult\u00f3rio.<\/p>\n<h4>8 &#8211; Tenha as informa\u00e7\u00f5es sempre \u00e0 m\u00e3o<\/h4>\n<p>Quando o paciente ligar, \u00e9 imprescind\u00edvel que voc\u00ea <strong>encontre as informa\u00e7\u00f5es<\/strong> do mesmo de<strong> forma r\u00e1pida<\/strong>. Um <a href=\"https:\/\/prodoctor.net\" target=\"_blank\" rel=\"noopener noreferrer\">software de gest\u00e3o de cl\u00ednicas e consult\u00f3rios<\/a> pode auxiliar nessa tarefa.<\/p>\n<p>Com ele \u00e9 poss\u00edvel localizar a ficha do paciente, ou criar uma nova, e marcar a consulta de <strong>forma r\u00e1pida e segura<\/strong>. Al\u00e9m de demonstrar <strong>efici\u00eancia<\/strong>, <strong>n\u00e3o ocupa a linha telef\u00f4nica<\/strong> e <strong>evita erros<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Responsabilidade, educa\u00e7\u00e3o e paci\u00eancia s\u00e3o algumas das exig\u00eancias de como melhorar o atendimento telef\u00f4nico do seu local de trabalho&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":7237,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[412],"tags":[],"class_list":["post-7234","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gestao-de-clinicas-e-consultorios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Como melhorar o atendimento telef\u00f4nico de cl\u00ednicas e consult\u00f3rios<\/title>\n<meta name=\"description\" content=\"Responsabilidade, educa\u00e7\u00e3o e paci\u00eancia s\u00e3o algumas das exig\u00eancias de como melhorar o atendimento telef\u00f4nico do seu local de trabalho. Veja como melhorar!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prodoctor.net\/blog\/melhorar-atendimento-telefonico-de-clinicas-consultorios\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como melhorar o atendimento telef\u00f4nico de cl\u00ednicas e consult\u00f3rios\" \/>\n<meta property=\"og:description\" content=\"Responsabilidade, educa\u00e7\u00e3o e paci\u00eancia s\u00e3o algumas das exig\u00eancias de como melhorar o atendimento telef\u00f4nico do seu local de trabalho. Veja como melhorar!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prodoctor.net\/blog\/melhorar-atendimento-telefonico-de-clinicas-consultorios\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog ProDoctor\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prodoctorsoftware\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-19T14:47:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-01T13:57:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2018\/02\/melhorar-atendimento-telefonico-clinica-consultorio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"770\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ProDoctor Software\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@prodoctorsoft\" \/>\n<meta name=\"twitter:site\" content=\"@prodoctorsoft\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ProDoctor Software\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/prodoctor.net\/blog\/melhorar-atendimento-telefonico-de-clinicas-consultorios\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/melhorar-atendimento-telefonico-de-clinicas-consultorios\/\"},\"author\":{\"name\":\"ProDoctor Software\",\"@id\":\"https:\/\/prodoctor.net\/blog\/#\/schema\/person\/8878914b17cd360e7ec0ddee1ed8c544\"},\"headline\":\"Como melhorar o atendimento telef\u00f4nico de cl\u00ednicas e consult\u00f3rios\",\"datePublished\":\"2018-02-19T14:47:40+00:00\",\"dateModified\":\"2019-04-01T13:57:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/melhorar-atendimento-telefonico-de-clinicas-consultorios\/\"},\"wordCount\":973,\"publisher\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/melhorar-atendimento-telefonico-de-clinicas-consultorios\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2018\/02\/melhorar-atendimento-telefonico-clinica-consultorio.jpg\",\"articleSection\":[\"Gest\u00e3o de Cl\u00ednicas e Consult\u00f3rios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/prodoctor.net\/blog\/melhorar-atendimento-telefonico-de-clinicas-consultorios\/\",\"url\":\"https:\/\/prodoctor.net\/blog\/melhorar-atendimento-telefonico-de-clinicas-consultorios\/\",\"name\":\"Como melhorar o atendimento telef\u00f4nico de cl\u00ednicas e consult\u00f3rios\",\"isPartOf\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/melhorar-atendimento-telefonico-de-clinicas-consultorios\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/melhorar-atendimento-telefonico-de-clinicas-consultorios\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2018\/02\/melhorar-atendimento-telefonico-clinica-consultorio.jpg\",\"datePublished\":\"2018-02-19T14:47:40+00:00\",\"dateModified\":\"2019-04-01T13:57:33+00:00\",\"description\":\"Responsabilidade, educa\u00e7\u00e3o e paci\u00eancia s\u00e3o algumas das exig\u00eancias de como melhorar o atendimento telef\u00f4nico do seu local de trabalho. Veja como melhorar!\",\"breadcrumb\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/melhorar-atendimento-telefonico-de-clinicas-consultorios\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/prodoctor.net\/blog\/melhorar-atendimento-telefonico-de-clinicas-consultorios\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/prodoctor.net\/blog\/melhorar-atendimento-telefonico-de-clinicas-consultorios\/#primaryimage\",\"url\":\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2018\/02\/melhorar-atendimento-telefonico-clinica-consultorio.jpg\",\"contentUrl\":\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2018\/02\/melhorar-atendimento-telefonico-clinica-consultorio.jpg\",\"width\":770,\"height\":400,\"caption\":\"Como melhorar o atendimento telef\u00f4nico de sua cl\u00ednica\/consult\u00f3rio\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/prodoctor.net\/blog\/melhorar-atendimento-telefonico-de-clinicas-consultorios\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/prodoctor.net\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como melhorar o atendimento telef\u00f4nico de cl\u00ednicas e consult\u00f3rios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/prodoctor.net\/blog\/#website\",\"url\":\"https:\/\/prodoctor.net\/blog\/\",\"name\":\"Blog ProDoctor\",\"description\":\"Tudo sobre o mundo da Sa\u00fade\",\"publisher\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/prodoctor.net\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/prodoctor.net\/blog\/#organization\",\"name\":\"ProDoctor Software S\/A\",\"url\":\"https:\/\/prodoctor.net\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/prodoctor.net\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2017\/01\/Logo_PDo_Lateral.png\",\"contentUrl\":\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2017\/01\/Logo_PDo_Lateral.png\",\"width\":2014,\"height\":485,\"caption\":\"ProDoctor Software S\/A\"},\"image\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/prodoctorsoftware\",\"https:\/\/x.com\/prodoctorsoft\",\"https:\/\/www.instagram.com\/prodoctorsoftware\/\",\"https:\/\/www.linkedin.com\/company\/prodoctor-software-ltda\",\"https:\/\/www.youtube.com\/channel\/UCIWuDLsVtIpX-PEqQn1pNlw\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/prodoctor.net\/blog\/#\/schema\/person\/8878914b17cd360e7ec0ddee1ed8c544\",\"name\":\"ProDoctor Software\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/prodoctor.net\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a67bdb10f2e6695f7ae356a84deeaf10b545567f0ac054e9bfe8ec56e86317ec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a67bdb10f2e6695f7ae356a84deeaf10b545567f0ac054e9bfe8ec56e86317ec?s=96&d=mm&r=g\",\"caption\":\"ProDoctor Software\"},\"sameAs\":[\"http:\/\/prodoctor.net\",\"https:\/\/x.com\/prodoctorsoft\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como melhorar o atendimento telef\u00f4nico de cl\u00ednicas e consult\u00f3rios","description":"Responsabilidade, educa\u00e7\u00e3o e paci\u00eancia s\u00e3o algumas das exig\u00eancias de como melhorar o atendimento telef\u00f4nico do seu local de trabalho. Veja como melhorar!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prodoctor.net\/blog\/melhorar-atendimento-telefonico-de-clinicas-consultorios\/","og_locale":"pt_BR","og_type":"article","og_title":"Como melhorar o atendimento telef\u00f4nico de cl\u00ednicas e consult\u00f3rios","og_description":"Responsabilidade, educa\u00e7\u00e3o e paci\u00eancia s\u00e3o algumas das exig\u00eancias de como melhorar o atendimento telef\u00f4nico do seu local de trabalho. Veja como melhorar!","og_url":"https:\/\/prodoctor.net\/blog\/melhorar-atendimento-telefonico-de-clinicas-consultorios\/","og_site_name":"Blog ProDoctor","article_publisher":"https:\/\/www.facebook.com\/prodoctorsoftware","article_published_time":"2018-02-19T14:47:40+00:00","article_modified_time":"2019-04-01T13:57:33+00:00","og_image":[{"width":770,"height":400,"url":"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2018\/02\/melhorar-atendimento-telefonico-clinica-consultorio.jpg","type":"image\/jpeg"}],"author":"ProDoctor Software","twitter_card":"summary_large_image","twitter_creator":"@prodoctorsoft","twitter_site":"@prodoctorsoft","twitter_misc":{"Escrito por":"ProDoctor Software","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prodoctor.net\/blog\/melhorar-atendimento-telefonico-de-clinicas-consultorios\/#article","isPartOf":{"@id":"https:\/\/prodoctor.net\/blog\/melhorar-atendimento-telefonico-de-clinicas-consultorios\/"},"author":{"name":"ProDoctor Software","@id":"https:\/\/prodoctor.net\/blog\/#\/schema\/person\/8878914b17cd360e7ec0ddee1ed8c544"},"headline":"Como melhorar o atendimento telef\u00f4nico de cl\u00ednicas e consult\u00f3rios","datePublished":"2018-02-19T14:47:40+00:00","dateModified":"2019-04-01T13:57:33+00:00","mainEntityOfPage":{"@id":"https:\/\/prodoctor.net\/blog\/melhorar-atendimento-telefonico-de-clinicas-consultorios\/"},"wordCount":973,"publisher":{"@id":"https:\/\/prodoctor.net\/blog\/#organization"},"image":{"@id":"https:\/\/prodoctor.net\/blog\/melhorar-atendimento-telefonico-de-clinicas-consultorios\/#primaryimage"},"thumbnailUrl":"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2018\/02\/melhorar-atendimento-telefonico-clinica-consultorio.jpg","articleSection":["Gest\u00e3o de Cl\u00ednicas e Consult\u00f3rios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/prodoctor.net\/blog\/melhorar-atendimento-telefonico-de-clinicas-consultorios\/","url":"https:\/\/prodoctor.net\/blog\/melhorar-atendimento-telefonico-de-clinicas-consultorios\/","name":"Como melhorar o atendimento telef\u00f4nico de cl\u00ednicas e consult\u00f3rios","isPartOf":{"@id":"https:\/\/prodoctor.net\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prodoctor.net\/blog\/melhorar-atendimento-telefonico-de-clinicas-consultorios\/#primaryimage"},"image":{"@id":"https:\/\/prodoctor.net\/blog\/melhorar-atendimento-telefonico-de-clinicas-consultorios\/#primaryimage"},"thumbnailUrl":"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2018\/02\/melhorar-atendimento-telefonico-clinica-consultorio.jpg","datePublished":"2018-02-19T14:47:40+00:00","dateModified":"2019-04-01T13:57:33+00:00","description":"Responsabilidade, educa\u00e7\u00e3o e paci\u00eancia s\u00e3o algumas das exig\u00eancias de como melhorar o atendimento telef\u00f4nico do seu local de trabalho. Veja como melhorar!","breadcrumb":{"@id":"https:\/\/prodoctor.net\/blog\/melhorar-atendimento-telefonico-de-clinicas-consultorios\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prodoctor.net\/blog\/melhorar-atendimento-telefonico-de-clinicas-consultorios\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/prodoctor.net\/blog\/melhorar-atendimento-telefonico-de-clinicas-consultorios\/#primaryimage","url":"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2018\/02\/melhorar-atendimento-telefonico-clinica-consultorio.jpg","contentUrl":"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2018\/02\/melhorar-atendimento-telefonico-clinica-consultorio.jpg","width":770,"height":400,"caption":"Como melhorar o atendimento telef\u00f4nico de sua cl\u00ednica\/consult\u00f3rio"},{"@type":"BreadcrumbList","@id":"https:\/\/prodoctor.net\/blog\/melhorar-atendimento-telefonico-de-clinicas-consultorios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/prodoctor.net\/blog\/"},{"@type":"ListItem","position":2,"name":"Como melhorar o atendimento telef\u00f4nico de cl\u00ednicas e consult\u00f3rios"}]},{"@type":"WebSite","@id":"https:\/\/prodoctor.net\/blog\/#website","url":"https:\/\/prodoctor.net\/blog\/","name":"Blog ProDoctor","description":"Tudo sobre o mundo da Sa\u00fade","publisher":{"@id":"https:\/\/prodoctor.net\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prodoctor.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/prodoctor.net\/blog\/#organization","name":"ProDoctor Software S\/A","url":"https:\/\/prodoctor.net\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/prodoctor.net\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2017\/01\/Logo_PDo_Lateral.png","contentUrl":"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2017\/01\/Logo_PDo_Lateral.png","width":2014,"height":485,"caption":"ProDoctor Software S\/A"},"image":{"@id":"https:\/\/prodoctor.net\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prodoctorsoftware","https:\/\/x.com\/prodoctorsoft","https:\/\/www.instagram.com\/prodoctorsoftware\/","https:\/\/www.linkedin.com\/company\/prodoctor-software-ltda","https:\/\/www.youtube.com\/channel\/UCIWuDLsVtIpX-PEqQn1pNlw"]},{"@type":"Person","@id":"https:\/\/prodoctor.net\/blog\/#\/schema\/person\/8878914b17cd360e7ec0ddee1ed8c544","name":"ProDoctor Software","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/prodoctor.net\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a67bdb10f2e6695f7ae356a84deeaf10b545567f0ac054e9bfe8ec56e86317ec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a67bdb10f2e6695f7ae356a84deeaf10b545567f0ac054e9bfe8ec56e86317ec?s=96&d=mm&r=g","caption":"ProDoctor Software"},"sameAs":["http:\/\/prodoctor.net","https:\/\/x.com\/prodoctorsoft"]}]}},"taxonomy_info":{"category":[{"value":412,"label":"Gest\u00e3o de Cl\u00ednicas e Consult\u00f3rios"}]},"featured_image_src_large":["https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2018\/02\/melhorar-atendimento-telefonico-clinica-consultorio.jpg",770,400,false],"author_info":{"display_name":"ProDoctor Software","author_link":"https:\/\/prodoctor.net\/blog\/author\/redesocialprodoctor-net\/"},"comment_info":2,"category_info":[{"term_id":412,"name":"Gest\u00e3o de Cl\u00ednicas e Consult\u00f3rios","slug":"gestao-de-clinicas-e-consultorios","term_group":0,"term_taxonomy_id":412,"taxonomy":"category","description":"","parent":0,"count":299,"filter":"raw","cat_ID":412,"category_count":299,"category_description":"","cat_name":"Gest\u00e3o de Cl\u00ednicas e Consult\u00f3rios","category_nicename":"gestao-de-clinicas-e-consultorios","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/posts\/7234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/comments?post=7234"}],"version-history":[{"count":11,"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/posts\/7234\/revisions"}],"predecessor-version":[{"id":11422,"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/posts\/7234\/revisions\/11422"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/media\/7237"}],"wp:attachment":[{"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/media?parent=7234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/categories?post=7234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/tags?post=7234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}