{"id":192,"date":"2018-01-13T10:00:28","date_gmt":"2018-01-13T13:00:28","guid":{"rendered":"http:\/\/blog.prodoctor.net\/?p=192"},"modified":"2021-07-26T14:59:08","modified_gmt":"2021-07-26T17:59:08","slug":"como-evitar-atrasos-dos-pacientes","status":"publish","type":"post","link":"https:\/\/prodoctor.net\/blog\/como-evitar-atrasos-dos-pacientes\/","title":{"rendered":"Como evitar atrasos dos pacientes"},"content":{"rendered":"<p>Voc\u00ea sabe <strong>como evitar atrasos dos pacientes<\/strong>? Sim, isso \u00e9 poss\u00edvel! Imprevistos acontecem a<strong> qualquer um e a qualquer momento<\/strong>. Quem trabalha com<strong> hor\u00e1rios agendados para atendimentos<\/strong> deve estar cansado de <strong>tomar os famosos \u2018bolos\u2019<\/strong>.<\/p>\n<p>Voc\u00ea tem toda uma agenda planejada, hor\u00e1rios apertados, a\u00ed um paciente atrasa. Consequentemente, a partir da\u00ed, <strong>o restante da sua agenda vai atrasar tamb\u00e9m<\/strong>. E existem aqueles que faltam aos agendamentos tamb\u00e9m e <strong>fica aquele hor\u00e1rio<\/strong> vago na agenda. \u00c0s vezes consegue-se <strong>encaixar outro paciente<\/strong> no hor\u00e1rio, \u00e0s vezes n\u00e3o e a\u00ed pode acontecer o preju\u00edzo. Afinal, o hor\u00e1rio era para se estar trabalhando.<\/p>\n<p>Os motivos que levam algu\u00e9m a faltar um compromisso agendado s\u00e3o os mais variados poss\u00edveis. O paciente pode ter passado mal, perdido a hora ou teve que ir buscar o filho na escola. E o principal e talvez o mais comum: <strong>a pessoa esqueceu da consulta<\/strong>. Para os demais casos n\u00e3o h\u00e1 rem\u00e9dio, mas <strong>para o esquecimento h\u00e1 meios de tentar evit\u00e1-lo<\/strong>.<\/p>\n<h2>Como evitar atrasos dos pacientes?<\/h2>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-18914 size-full\" title=\"Como evitar atrasos dos pacientes?\" src=\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2021\/04\/atendimento-preferencial5-min.jpg\" alt=\"Como evitar atrasos dos pacientes?\" width=\"770\" height=\"251\" srcset=\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2021\/04\/atendimento-preferencial5-min.jpg 770w, https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2021\/04\/atendimento-preferencial5-min-300x98.jpg 300w, https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2021\/04\/atendimento-preferencial5-min-768x250.jpg 768w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/p>\n<h3>Lembretes!<\/h3>\n<p>O meio mais utilizado para <strong>lembrar ao paciente de sua consulta<\/strong> \u00e9 a liga\u00e7\u00e3o telef\u00f4nica. A secret\u00e1ria, \u00e0s v\u00e9speras do agendamento, faz uma liga\u00e7\u00e3o ao paciente e confirma a presen\u00e7a do mesmo ao compromisso. Por\u00e9m, <strong>podemos citar alguns contras dessa modalidade<\/strong>, como: altos custos com liga\u00e7\u00f5es telef\u00f4nicas no m\u00eas, perturba\u00e7\u00e3o do paciente em momentos o qual ele n\u00e3o gostaria de receber liga\u00e7\u00f5es e sobrecarga de tarefa sobre a secret\u00e1ria (afinal ela ainda tem que atender ao telefone, realizar agendamentos, recepcionar os pacientes e por a\u00ed vai).<\/p>\n<p>Outro meio de lembrar \u00e9 <strong>utilizar o envio de emails aos pacientes<\/strong>. N\u00e3o possui custo nenhum e \u00e9 r\u00e1pido, pois basta voc\u00ea ter uma conta de e-mail ativa, os endere\u00e7os de emails de destino de seus pacientes, escrever uma mensagem padr\u00e3o e enviar. Por\u00e9m, como nem tudo s\u00e3o flores, podemos citar os contras: <strong>nem todo mundo tem ou sabe utilizar uma conta de e-mail<\/strong>, o endere\u00e7o de e-mail n\u00e3o pode ter um errinho,\u00a0pode cair na caixa de spams e o usu\u00e1rio delet\u00e1-lo impiedosamente e sequer desconfiar que um dia ele esteve ali.<\/p>\n<h4>Temos uma dica de como evitar atrasos dos pacientes!<\/h4>\n<p>Atualmente, <strong>um dos melhores meios de se lembrar um paciente<\/strong> sobre sua consulta agendada <strong>pode ser um <a href=\"https:\/\/pt.wikipedia.org\/wiki\/Servi%C3%A7o_de_mensagens_curtas\" target=\"_blank\" rel=\"noopener\">SMS<\/a><\/strong> (a famosa mensagem de texto do celular). Sabe porqu\u00ea? N\u00e3o \u00e9 invasivo, a pessoa l\u00ea a mensagem a hora que puder e quiser, independentemente da hora em que a recebeu. \u00c9 barato e voc\u00ea ainda pode automatizar este processo, contratando servi\u00e7os de envio ou <strong>utilizando de um software que faz este servi\u00e7o para voc\u00ea.<\/strong><\/p>\n<p>Como \u00e9 o caso do <a href=\"https:\/\/prodoctor.net\/corp\" target=\"_blank\" rel=\"noopener\">ProDoctor Corp<\/a> e <a href=\"https:\/\/prodoctor.net\/plus\" target=\"_blank\" rel=\"noopener\">ProDoctor Plus<\/a>, onde basta voc\u00ea conectar um modem 3G de sua operadora em seu computador, configurar a mensagem padr\u00e3o desejada e selecionar quais <strong>os agendamentos de pacientes que devem receber o lembrete <\/strong>e\u00a0pronto! Todos os pacientes em quest\u00e3o ser\u00e3o alertados de seus compromissos. R\u00e1pido, f\u00e1cil, confi\u00e1vel e barato, apesar de se utilizar de um modem 3G, este processo n\u00e3o utiliza da internet para realizar o envio.<\/p>\n<p>Se voc\u00ea parar para pensar, h\u00e1<strong> muitas formas de se lembrar um paciente de uma consulta<\/strong>, mas \u00e9 preciso cuidado, pois <strong>certos meios podem ser considerados invasivos<\/strong> e podem chatear seus pacientes. Para lhe ajudar tamb\u00e9m nesse desafio, fizemos um post sobre <em>O que fazer para seus pacientes n\u00e3o faltarem as consultas.\u00a0<\/em>Voc\u00ea pode ter acesso a ele <a href=\"https:\/\/prodoctor.net\/blog\/o-que-fazer-para-seus-pacientes-nao-faltarem-as-consultas\/\" target=\"_blank\" rel=\"noopener\">clicando aqui<\/a>.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea sabe como evitar atrasos dos pacientes? Sim, isso \u00e9 poss\u00edvel! Imprevistos acontecem a qualquer um e a qualquer&#8230;<\/p>\n","protected":false},"author":1,"featured_media":14745,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[412],"tags":[61,53,54,58,55,60,56,404,405,57,59],"class_list":["post-192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gestao-de-clinicas-e-consultorios","tag-agenda","tag-agendamento","tag-compromisso","tag-email","tag-falta","tag-imprevistos","tag-infrequencia","tag-prodoctor-corp","tag-prodoctor-plus","tag-sms","tag-telefone-economia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Como evitar atrasos dos pacientes - Blog ProDoctor Software<\/title>\n<meta name=\"description\" content=\"Imprevistos acontecem a qualquer um e a qualquer momento, mas para o esquecimento h\u00e1 meios de tentar evit\u00e1-lo. Saiba como evitar atrasos dos pacientes!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prodoctor.net\/blog\/como-evitar-atrasos-dos-pacientes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como evitar atrasos dos pacientes - Blog ProDoctor Software\" \/>\n<meta property=\"og:description\" content=\"Imprevistos acontecem a qualquer um e a qualquer momento, mas para o esquecimento h\u00e1 meios de tentar evit\u00e1-lo. Saiba como evitar atrasos dos pacientes!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prodoctor.net\/blog\/como-evitar-atrasos-dos-pacientes\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog ProDoctor\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prodoctorsoftware\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-13T13:00:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-26T17:59:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2020\/01\/sistema_agenda_clinica_medica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"599\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ProDoctor Software\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@prodoctorsoft\" \/>\n<meta name=\"twitter:site\" content=\"@prodoctorsoft\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ProDoctor Software\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/prodoctor.net\/blog\/como-evitar-atrasos-dos-pacientes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/como-evitar-atrasos-dos-pacientes\/\"},\"author\":{\"name\":\"ProDoctor Software\",\"@id\":\"https:\/\/prodoctor.net\/blog\/#\/schema\/person\/8878914b17cd360e7ec0ddee1ed8c544\"},\"headline\":\"Como evitar atrasos dos pacientes\",\"datePublished\":\"2018-01-13T13:00:28+00:00\",\"dateModified\":\"2021-07-26T17:59:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/como-evitar-atrasos-dos-pacientes\/\"},\"wordCount\":611,\"publisher\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/como-evitar-atrasos-dos-pacientes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2020\/01\/sistema_agenda_clinica_medica.jpg\",\"keywords\":[\"agenda\",\"agendamento\",\"compromisso\",\"email\",\"falta\",\"imprevistos\",\"infrequ\u00eancia\",\"ProDoctor Corp\",\"ProDoctor Plus\",\"sms\",\"telefone. economia\"],\"articleSection\":[\"Gest\u00e3o de Cl\u00ednicas e Consult\u00f3rios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/prodoctor.net\/blog\/como-evitar-atrasos-dos-pacientes\/\",\"url\":\"https:\/\/prodoctor.net\/blog\/como-evitar-atrasos-dos-pacientes\/\",\"name\":\"Como evitar atrasos dos pacientes - Blog ProDoctor Software\",\"isPartOf\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/como-evitar-atrasos-dos-pacientes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/como-evitar-atrasos-dos-pacientes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2020\/01\/sistema_agenda_clinica_medica.jpg\",\"datePublished\":\"2018-01-13T13:00:28+00:00\",\"dateModified\":\"2021-07-26T17:59:08+00:00\",\"description\":\"Imprevistos acontecem a qualquer um e a qualquer momento, mas para o esquecimento h\u00e1 meios de tentar evit\u00e1-lo. Saiba como evitar atrasos dos pacientes!\",\"breadcrumb\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/como-evitar-atrasos-dos-pacientes\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/prodoctor.net\/blog\/como-evitar-atrasos-dos-pacientes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/prodoctor.net\/blog\/como-evitar-atrasos-dos-pacientes\/#primaryimage\",\"url\":\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2020\/01\/sistema_agenda_clinica_medica.jpg\",\"contentUrl\":\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2020\/01\/sistema_agenda_clinica_medica.jpg\",\"width\":1000,\"height\":599},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/prodoctor.net\/blog\/como-evitar-atrasos-dos-pacientes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/prodoctor.net\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como evitar atrasos dos pacientes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/prodoctor.net\/blog\/#website\",\"url\":\"https:\/\/prodoctor.net\/blog\/\",\"name\":\"Blog ProDoctor\",\"description\":\"Tudo sobre o mundo da Sa\u00fade\",\"publisher\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/prodoctor.net\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/prodoctor.net\/blog\/#organization\",\"name\":\"ProDoctor Software S\/A\",\"url\":\"https:\/\/prodoctor.net\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/prodoctor.net\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2017\/01\/Logo_PDo_Lateral.png\",\"contentUrl\":\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2017\/01\/Logo_PDo_Lateral.png\",\"width\":2014,\"height\":485,\"caption\":\"ProDoctor Software S\/A\"},\"image\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/prodoctorsoftware\",\"https:\/\/x.com\/prodoctorsoft\",\"https:\/\/www.instagram.com\/prodoctorsoftware\/\",\"https:\/\/www.linkedin.com\/company\/prodoctor-software-ltda\",\"https:\/\/www.youtube.com\/channel\/UCIWuDLsVtIpX-PEqQn1pNlw\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/prodoctor.net\/blog\/#\/schema\/person\/8878914b17cd360e7ec0ddee1ed8c544\",\"name\":\"ProDoctor Software\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/prodoctor.net\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a67bdb10f2e6695f7ae356a84deeaf10b545567f0ac054e9bfe8ec56e86317ec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a67bdb10f2e6695f7ae356a84deeaf10b545567f0ac054e9bfe8ec56e86317ec?s=96&d=mm&r=g\",\"caption\":\"ProDoctor Software\"},\"sameAs\":[\"http:\/\/prodoctor.net\",\"https:\/\/x.com\/prodoctorsoft\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como evitar atrasos dos pacientes - Blog ProDoctor Software","description":"Imprevistos acontecem a qualquer um e a qualquer momento, mas para o esquecimento h\u00e1 meios de tentar evit\u00e1-lo. Saiba como evitar atrasos dos pacientes!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prodoctor.net\/blog\/como-evitar-atrasos-dos-pacientes\/","og_locale":"pt_BR","og_type":"article","og_title":"Como evitar atrasos dos pacientes - Blog ProDoctor Software","og_description":"Imprevistos acontecem a qualquer um e a qualquer momento, mas para o esquecimento h\u00e1 meios de tentar evit\u00e1-lo. Saiba como evitar atrasos dos pacientes!","og_url":"https:\/\/prodoctor.net\/blog\/como-evitar-atrasos-dos-pacientes\/","og_site_name":"Blog ProDoctor","article_publisher":"https:\/\/www.facebook.com\/prodoctorsoftware","article_published_time":"2018-01-13T13:00:28+00:00","article_modified_time":"2021-07-26T17:59:08+00:00","og_image":[{"width":1000,"height":599,"url":"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2020\/01\/sistema_agenda_clinica_medica.jpg","type":"image\/jpeg"}],"author":"ProDoctor Software","twitter_card":"summary_large_image","twitter_creator":"@prodoctorsoft","twitter_site":"@prodoctorsoft","twitter_misc":{"Escrito por":"ProDoctor Software","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prodoctor.net\/blog\/como-evitar-atrasos-dos-pacientes\/#article","isPartOf":{"@id":"https:\/\/prodoctor.net\/blog\/como-evitar-atrasos-dos-pacientes\/"},"author":{"name":"ProDoctor Software","@id":"https:\/\/prodoctor.net\/blog\/#\/schema\/person\/8878914b17cd360e7ec0ddee1ed8c544"},"headline":"Como evitar atrasos dos pacientes","datePublished":"2018-01-13T13:00:28+00:00","dateModified":"2021-07-26T17:59:08+00:00","mainEntityOfPage":{"@id":"https:\/\/prodoctor.net\/blog\/como-evitar-atrasos-dos-pacientes\/"},"wordCount":611,"publisher":{"@id":"https:\/\/prodoctor.net\/blog\/#organization"},"image":{"@id":"https:\/\/prodoctor.net\/blog\/como-evitar-atrasos-dos-pacientes\/#primaryimage"},"thumbnailUrl":"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2020\/01\/sistema_agenda_clinica_medica.jpg","keywords":["agenda","agendamento","compromisso","email","falta","imprevistos","infrequ\u00eancia","ProDoctor Corp","ProDoctor Plus","sms","telefone. economia"],"articleSection":["Gest\u00e3o de Cl\u00ednicas e Consult\u00f3rios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/prodoctor.net\/blog\/como-evitar-atrasos-dos-pacientes\/","url":"https:\/\/prodoctor.net\/blog\/como-evitar-atrasos-dos-pacientes\/","name":"Como evitar atrasos dos pacientes - Blog ProDoctor Software","isPartOf":{"@id":"https:\/\/prodoctor.net\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prodoctor.net\/blog\/como-evitar-atrasos-dos-pacientes\/#primaryimage"},"image":{"@id":"https:\/\/prodoctor.net\/blog\/como-evitar-atrasos-dos-pacientes\/#primaryimage"},"thumbnailUrl":"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2020\/01\/sistema_agenda_clinica_medica.jpg","datePublished":"2018-01-13T13:00:28+00:00","dateModified":"2021-07-26T17:59:08+00:00","description":"Imprevistos acontecem a qualquer um e a qualquer momento, mas para o esquecimento h\u00e1 meios de tentar evit\u00e1-lo. Saiba como evitar atrasos dos pacientes!","breadcrumb":{"@id":"https:\/\/prodoctor.net\/blog\/como-evitar-atrasos-dos-pacientes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prodoctor.net\/blog\/como-evitar-atrasos-dos-pacientes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/prodoctor.net\/blog\/como-evitar-atrasos-dos-pacientes\/#primaryimage","url":"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2020\/01\/sistema_agenda_clinica_medica.jpg","contentUrl":"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2020\/01\/sistema_agenda_clinica_medica.jpg","width":1000,"height":599},{"@type":"BreadcrumbList","@id":"https:\/\/prodoctor.net\/blog\/como-evitar-atrasos-dos-pacientes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/prodoctor.net\/blog\/"},{"@type":"ListItem","position":2,"name":"Como evitar atrasos dos pacientes"}]},{"@type":"WebSite","@id":"https:\/\/prodoctor.net\/blog\/#website","url":"https:\/\/prodoctor.net\/blog\/","name":"Blog ProDoctor","description":"Tudo sobre o mundo da Sa\u00fade","publisher":{"@id":"https:\/\/prodoctor.net\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prodoctor.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/prodoctor.net\/blog\/#organization","name":"ProDoctor Software S\/A","url":"https:\/\/prodoctor.net\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/prodoctor.net\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2017\/01\/Logo_PDo_Lateral.png","contentUrl":"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2017\/01\/Logo_PDo_Lateral.png","width":2014,"height":485,"caption":"ProDoctor Software S\/A"},"image":{"@id":"https:\/\/prodoctor.net\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prodoctorsoftware","https:\/\/x.com\/prodoctorsoft","https:\/\/www.instagram.com\/prodoctorsoftware\/","https:\/\/www.linkedin.com\/company\/prodoctor-software-ltda","https:\/\/www.youtube.com\/channel\/UCIWuDLsVtIpX-PEqQn1pNlw"]},{"@type":"Person","@id":"https:\/\/prodoctor.net\/blog\/#\/schema\/person\/8878914b17cd360e7ec0ddee1ed8c544","name":"ProDoctor Software","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/prodoctor.net\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a67bdb10f2e6695f7ae356a84deeaf10b545567f0ac054e9bfe8ec56e86317ec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a67bdb10f2e6695f7ae356a84deeaf10b545567f0ac054e9bfe8ec56e86317ec?s=96&d=mm&r=g","caption":"ProDoctor Software"},"sameAs":["http:\/\/prodoctor.net","https:\/\/x.com\/prodoctorsoft"]}]}},"taxonomy_info":{"category":[{"value":412,"label":"Gest\u00e3o de Cl\u00ednicas e Consult\u00f3rios"}],"post_tag":[{"value":61,"label":"agenda"},{"value":53,"label":"agendamento"},{"value":54,"label":"compromisso"},{"value":58,"label":"email"},{"value":55,"label":"falta"},{"value":60,"label":"imprevistos"},{"value":56,"label":"infrequ\u00eancia"},{"value":404,"label":"ProDoctor Corp"},{"value":405,"label":"ProDoctor Plus"},{"value":57,"label":"sms"},{"value":59,"label":"telefone. economia"}]},"featured_image_src_large":["https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2020\/01\/sistema_agenda_clinica_medica.jpg",1000,599,false],"author_info":{"display_name":"ProDoctor Software","author_link":"https:\/\/prodoctor.net\/blog\/author\/redesocialprodoctor-net\/"},"comment_info":0,"category_info":[{"term_id":412,"name":"Gest\u00e3o de Cl\u00ednicas e Consult\u00f3rios","slug":"gestao-de-clinicas-e-consultorios","term_group":0,"term_taxonomy_id":412,"taxonomy":"category","description":"","parent":0,"count":299,"filter":"raw","cat_ID":412,"category_count":299,"category_description":"","cat_name":"Gest\u00e3o de Cl\u00ednicas e Consult\u00f3rios","category_nicename":"gestao-de-clinicas-e-consultorios","category_parent":0}],"tag_info":[{"term_id":61,"name":"agenda","slug":"agenda","term_group":0,"term_taxonomy_id":64,"taxonomy":"post_tag","description":"","parent":0,"count":4,"filter":"raw"},{"term_id":53,"name":"agendamento","slug":"agendamento","term_group":0,"term_taxonomy_id":56,"taxonomy":"post_tag","description":"","parent":0,"count":4,"filter":"raw"},{"term_id":54,"name":"compromisso","slug":"compromisso","term_group":0,"term_taxonomy_id":57,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw"},{"term_id":58,"name":"email","slug":"email","term_group":0,"term_taxonomy_id":61,"taxonomy":"post_tag","description":"","parent":0,"count":2,"filter":"raw"},{"term_id":55,"name":"falta","slug":"falta","term_group":0,"term_taxonomy_id":58,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw"},{"term_id":60,"name":"imprevistos","slug":"imprevistos","term_group":0,"term_taxonomy_id":63,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw"},{"term_id":56,"name":"infrequ\u00eancia","slug":"infrequencia","term_group":0,"term_taxonomy_id":59,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw"},{"term_id":404,"name":"ProDoctor Corp","slug":"prodoctor-corp","term_group":0,"term_taxonomy_id":4,"taxonomy":"post_tag","description":"","parent":0,"count":40,"filter":"raw"},{"term_id":405,"name":"ProDoctor Plus","slug":"prodoctor-plus","term_group":0,"term_taxonomy_id":5,"taxonomy":"post_tag","description":"","parent":0,"count":32,"filter":"raw"},{"term_id":57,"name":"sms","slug":"sms","term_group":0,"term_taxonomy_id":60,"taxonomy":"post_tag","description":"","parent":0,"count":3,"filter":"raw"},{"term_id":59,"name":"telefone. economia","slug":"telefone-economia","term_group":0,"term_taxonomy_id":62,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw"}],"_links":{"self":[{"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/posts\/192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/comments?post=192"}],"version-history":[{"count":11,"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/posts\/192\/revisions"}],"predecessor-version":[{"id":20465,"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/posts\/192\/revisions\/20465"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/media\/14745"}],"wp:attachment":[{"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/media?parent=192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/categories?post=192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/tags?post=192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}