{"id":18587,"date":"2021-03-15T14:53:33","date_gmt":"2021-03-15T17:53:33","guid":{"rendered":"https:\/\/prodoctor.net\/blog\/?p=18587"},"modified":"2024-02-28T16:19:33","modified_gmt":"2024-02-28T19:19:33","slug":"acesso-ao-prontuario-do-paciente","status":"publish","type":"post","link":"https:\/\/prodoctor.net\/blog\/acesso-ao-prontuario-do-paciente\/","title":{"rendered":"Acesso ao prontu\u00e1rio do paciente"},"content":{"rendered":"\n<p><span style=\"font-weight: 400;\">O Prontu\u00e1rio M\u00e9dico do Paciente \u00e9 um conjunto de documentos padronizados, ordenados e concisos, que servem para registro de todas as informa\u00e7\u00f5es referentes aos cuidados m\u00e9dicos e param\u00e9dicos prestados ao paciente.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">As informa\u00e7\u00f5es contidas no prontu\u00e1rio do paciente s\u00e3o sigilosas e n\u00e3o podem ser liberadas para qualquer um, visto que esse documento cont\u00e9m informa\u00e7\u00f5es importantes e pessoais a respeito dos pacientes e de sua sa\u00fade.<\/span>&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"font-weight: 400;\">Afinal, para que serve o prontu\u00e1rio do paciente?<\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2021\/03\/Novo-Projeto-46.png\"><img decoding=\"async\" width=\"770\" height=\"250\" src=\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2021\/03\/Novo-Projeto-46.png\" alt=\"Afinal, para que serve o prontu\u00e1rio do paciente?\" class=\"wp-image-18590\" srcset=\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2021\/03\/Novo-Projeto-46.png 770w, https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2021\/03\/Novo-Projeto-46-300x97.png 300w, https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2021\/03\/Novo-Projeto-46-768x249.png 768w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/a><\/figure>\n\n\n\n<p><span style=\"font-weight: 400;\">O prontu\u00e1rio do paciente ajuda a esclarecer d\u00favidas sobre exames e condutas terap\u00eauticas que o mesmo deve seguir e serve, principalmente, para facilitar a comunica\u00e7\u00e3o entre os profissionais da Sa\u00fade, seus pacientes e familiares.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">O profissional de Sa\u00fade que atender o paciente, deve garantir um prontu\u00e1rio bem feito, bem preenchido, sem rasuras, leg\u00edvel e com dados fidedignos. Assim, conseguir\u00e1 garantir que todos os outros profissionais que receberem esse prontu\u00e1rio para consultas futuras, pedidos ou receitu\u00e1rios de medicamentos, entendam facilmente o estado de sa\u00fade do paciente e consigam dar sequ\u00eancia ao seu tratamento.<\/span><\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<p class=\"has-text-align-center\"><a href=\"https:\/\/prodoctor.net\/blog\/sistema-de-prontuario-eletronico\/\" target=\"_blank\" rel=\"noreferrer noopener\">8 vantagens do prontu\u00e1rio digital<\/a><br><a href=\"https:\/\/prodoctor.net\/blog\/prontuario-do-paciente-versao-digital\/\" target=\"_blank\" rel=\"noreferrer noopener\">Tudo o que voc\u00ea precisa saber sobre prontu\u00e1rio digital<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"font-weight: 400;\">Quem pode ter acesso ao prontu\u00e1rio do paciente?<\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2021\/03\/Novo-Projeto-47.png\"><img decoding=\"async\" width=\"770\" height=\"250\" src=\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2021\/03\/Novo-Projeto-47.png\" alt=\"Quem pode ter acesso ao prontu\u00e1rio do paciente?\" class=\"wp-image-18591\" srcset=\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2021\/03\/Novo-Projeto-47.png 770w, https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2021\/03\/Novo-Projeto-47-300x97.png 300w, https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2021\/03\/Novo-Projeto-47-768x249.png 768w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/a><\/figure>\n\n\n\n<p><span style=\"font-weight: 400;\">De acordo com a Resolu\u00e7\u00e3o 1.605\/2000 do Conselho Federal de Medicina (CFM), apenas o paciente pode ter acesso \u00e0 c\u00f3pia do prontu\u00e1rio, salvo algumas exce\u00e7\u00f5es. Ao fazer esse tipo de solicita\u00e7\u00e3o, ser\u00e1 necess\u00e1rio preencher um requerimento e apresent\u00e1-lo junto com alguns documentos, tais como:<\/span><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><span style=\"font-weight: 400;\">c\u00f3pia do RG do paciente;<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">c\u00f3pia da certid\u00e3o de casamento ou, ent\u00e3o, o RG que conste essa informa\u00e7\u00e3o;<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">quando menor de idade, ser\u00e1 exigida a c\u00f3pia da certid\u00e3o de nascimento.<\/span><\/li>\n<\/ul>\n\n\n\n<p><span style=\"font-weight: 400;\">Em caso de falecimento, algum familiar pode solicitar a c\u00f3pia do prontu\u00e1rio. Para isso, \u00e9 preciso apresentar as seguintes documenta\u00e7\u00f5es:<\/span><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><span style=\"font-weight: 400;\">pais, filhos e demais familiares: c\u00f3pia do RG do paciente e requerente e da certid\u00e3o de \u00f3bito;&nbsp;<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">c\u00f4njuge: c\u00f3pia do RG do paciente, da certid\u00e3o de casamento e da certid\u00e3o de \u00f3bito;<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">procuradores: c\u00f3pia do RG do paciente e requerente e procura\u00e7\u00e3o.<\/span>&nbsp;<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"font-weight: 400;\">O que a legisla\u00e7\u00e3o diz acerca da guarda, acessibilidade e sigilo do prontu\u00e1rio?<\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2021\/03\/Novo-Projeto-48.png\"><img decoding=\"async\" width=\"770\" height=\"250\" src=\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2021\/03\/Novo-Projeto-48.png\" alt=\"O que a legisla\u00e7\u00e3o diz acerca da guarda, acessibilidade e sigilo do prontu\u00e1rio?\" class=\"wp-image-18592\" srcset=\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2021\/03\/Novo-Projeto-48.png 770w, https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2021\/03\/Novo-Projeto-48-300x97.png 300w, https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2021\/03\/Novo-Projeto-48-768x249.png 768w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/a><\/figure>\n\n\n\n<p><span style=\"font-weight: 400;\">A Resolu\u00e7\u00e3o 1.605\/2000 do CFM citada acima tem as seguintes exig\u00eancias a respeito da acessibilidade e sigilo do prontu\u00e1rio:&nbsp;<\/span><\/p>\n\n\n\n<p><i><span style=\"font-weight: 400;\"><strong>\u201cArt. 1\u00ba:<\/strong> O m\u00e9dico n\u00e3o pode, sem o consentimento do paciente, revelar o conte\u00fado do prontu\u00e1rio ou ficha m\u00e9dica.<\/span><\/i><\/p>\n\n\n\n<p><i><span style=\"font-weight: 400;\"><strong>Art. 2\u00ba:<\/strong> Nos casos do art. 269 do C\u00f3digo Penal, onde a comunica\u00e7\u00e3o de doen\u00e7a \u00e9 compuls\u00f3ria, o dever do m\u00e9dico restringe-se exclusivamente a comunicar tal fato \u00e0 autoridade competente, sendo proibida a remessa do prontu\u00e1rio m\u00e9dico do paciente.<\/span><\/i><\/p>\n\n\n\n<p><i><span style=\"font-weight: 400;\"><strong>Art. 3\u00ba:<\/strong> Na investiga\u00e7\u00e3o da hip\u00f3tese de cometimento de crime, o m\u00e9dico est\u00e1 impedido de revelar segredo que possa expor o paciente a processo criminal.<\/span><\/i><\/p>\n\n\n\n<p><i><span style=\"font-weight: 400;\"><strong>Art. 4\u00ba:<\/strong> Se na instru\u00e7\u00e3o de processo criminal for requisitada, por autoridade judici\u00e1ria competente, a apresenta\u00e7\u00e3o do conte\u00fado do prontu\u00e1rio ou da ficha m\u00e9dica, o m\u00e9dico disponibilizar\u00e1 os documentos ao perito nomeado pelo juiz, para que neles seja<\/span><\/i> <i><span style=\"font-weight: 400;\">realizada per\u00edcia restrita aos fatos em questionamento.<\/span><\/i><\/p>\n\n\n\n<p><i><span style=\"font-weight: 400;\"><strong>Art. 5\u00ba:<\/strong> Se houver autoriza\u00e7\u00e3o expressa do paciente, tanto na solicita\u00e7\u00e3o como em documento diverso, o m\u00e9dico poder\u00e1 encaminhar a ficha ou prontu\u00e1rio m\u00e9dico diretamente \u00e0 autoridade requisitante.<\/span><\/i><\/p>\n\n\n\n<p><i><span style=\"font-weight: 400;\"><strong>Art. 6\u00ba: <\/strong>O m\u00e9dico dever\u00e1 fornecer c\u00f3pia da ficha ou do prontu\u00e1rio m\u00e9dico desde que solicitado pelo paciente ou requisitado pelos Conselhos Federal ou Regional de Medicina.<\/span><\/i><\/p>\n\n\n\n<p><i><span style=\"font-weight: 400;\"><strong>Art. 7\u00ba:<\/strong> Para sua defesa judicial, o m\u00e9dico poder\u00e1 apresentar a ficha ou prontu\u00e1rio m\u00e9dico \u00e0 autoridade competente, solicitando que a mat\u00e9ria seja mantida em segredo de justi\u00e7a.<\/span><\/i><\/p>\n\n\n\n<p><i><span style=\"font-weight: 400;\"><strong>Art. 8\u00ba:<\/strong> Nos casos n\u00e3o previstos nesta resolu\u00e7\u00e3o e sempre que houver conflito no tocante \u00e0 remessa ou n\u00e3o dos documentos \u00e0 autoridade requisitante, o m\u00e9dico dever\u00e1 consultar o Conselho de Medicina, onde mant\u00e9m sua inscri\u00e7\u00e3o, quanto ao procedimento a ser adotado.\u201d<\/span><\/i><\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>O prontu\u00e1rio m\u00e9dico do paciente \u00e9 um conjunto de documentos padronizados, ordenados e concisos, que servem para registro de todas as informa\u00e7\u00f5es referentes aos cuidados m\u00e9dicos e param\u00e9dicos prestados ao paciente.<\/p>\n","protected":false},"author":1,"featured_media":18606,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[412],"tags":[],"class_list":["post-18587","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gestao-de-clinicas-e-consultorios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acesso ao prontu\u00e1rio do paciente - Blog ProDoctor<\/title>\n<meta name=\"description\" content=\"Como \u00e9 o acesso ao prontu\u00e1rio do paciente na sua cl\u00ednica ou consult\u00f3rio? Um documento t\u00e3o importante precisa de cuidados. Veja nossas dicas!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prodoctor.net\/blog\/acesso-ao-prontuario-do-paciente\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acesso ao prontu\u00e1rio do paciente - Blog ProDoctor\" \/>\n<meta property=\"og:description\" content=\"Como \u00e9 o acesso ao prontu\u00e1rio do paciente na sua cl\u00ednica ou consult\u00f3rio? Um documento t\u00e3o importante precisa de cuidados. Veja nossas dicas!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prodoctor.net\/blog\/acesso-ao-prontuario-do-paciente\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog ProDoctor\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prodoctorsoftware\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-15T17:53:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-28T19:19:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2021\/03\/legislacao.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"770\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ProDoctor Software\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@prodoctorsoft\" \/>\n<meta name=\"twitter:site\" content=\"@prodoctorsoft\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ProDoctor Software\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/prodoctor.net\/blog\/acesso-ao-prontuario-do-paciente\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/acesso-ao-prontuario-do-paciente\/\"},\"author\":{\"name\":\"ProDoctor Software\",\"@id\":\"https:\/\/prodoctor.net\/blog\/#\/schema\/person\/8878914b17cd360e7ec0ddee1ed8c544\"},\"headline\":\"Acesso ao prontu\u00e1rio do paciente\",\"datePublished\":\"2021-03-15T17:53:33+00:00\",\"dateModified\":\"2024-02-28T19:19:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/acesso-ao-prontuario-do-paciente\/\"},\"wordCount\":698,\"publisher\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/acesso-ao-prontuario-do-paciente\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2021\/03\/legislacao.jpg\",\"articleSection\":[\"Gest\u00e3o de Cl\u00ednicas e Consult\u00f3rios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/prodoctor.net\/blog\/acesso-ao-prontuario-do-paciente\/\",\"url\":\"https:\/\/prodoctor.net\/blog\/acesso-ao-prontuario-do-paciente\/\",\"name\":\"Acesso ao prontu\u00e1rio do paciente - Blog ProDoctor\",\"isPartOf\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/acesso-ao-prontuario-do-paciente\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/acesso-ao-prontuario-do-paciente\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2021\/03\/legislacao.jpg\",\"datePublished\":\"2021-03-15T17:53:33+00:00\",\"dateModified\":\"2024-02-28T19:19:33+00:00\",\"description\":\"Como \u00e9 o acesso ao prontu\u00e1rio do paciente na sua cl\u00ednica ou consult\u00f3rio? Um documento t\u00e3o importante precisa de cuidados. Veja nossas dicas!\",\"breadcrumb\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/acesso-ao-prontuario-do-paciente\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/prodoctor.net\/blog\/acesso-ao-prontuario-do-paciente\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/prodoctor.net\/blog\/acesso-ao-prontuario-do-paciente\/#primaryimage\",\"url\":\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2021\/03\/legislacao.jpg\",\"contentUrl\":\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2021\/03\/legislacao.jpg\",\"width\":770,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/prodoctor.net\/blog\/acesso-ao-prontuario-do-paciente\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/prodoctor.net\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acesso ao prontu\u00e1rio do paciente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/prodoctor.net\/blog\/#website\",\"url\":\"https:\/\/prodoctor.net\/blog\/\",\"name\":\"Blog ProDoctor\",\"description\":\"Tudo sobre o mundo da Sa\u00fade\",\"publisher\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/prodoctor.net\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/prodoctor.net\/blog\/#organization\",\"name\":\"ProDoctor Software S\/A\",\"url\":\"https:\/\/prodoctor.net\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/prodoctor.net\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2017\/01\/Logo_PDo_Lateral.png\",\"contentUrl\":\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2017\/01\/Logo_PDo_Lateral.png\",\"width\":2014,\"height\":485,\"caption\":\"ProDoctor Software S\/A\"},\"image\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/prodoctorsoftware\",\"https:\/\/x.com\/prodoctorsoft\",\"https:\/\/www.instagram.com\/prodoctorsoftware\/\",\"https:\/\/www.linkedin.com\/company\/prodoctor-software-ltda\",\"https:\/\/www.youtube.com\/channel\/UCIWuDLsVtIpX-PEqQn1pNlw\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/prodoctor.net\/blog\/#\/schema\/person\/8878914b17cd360e7ec0ddee1ed8c544\",\"name\":\"ProDoctor Software\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/prodoctor.net\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a67bdb10f2e6695f7ae356a84deeaf10b545567f0ac054e9bfe8ec56e86317ec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a67bdb10f2e6695f7ae356a84deeaf10b545567f0ac054e9bfe8ec56e86317ec?s=96&d=mm&r=g\",\"caption\":\"ProDoctor Software\"},\"sameAs\":[\"http:\/\/prodoctor.net\",\"https:\/\/x.com\/prodoctorsoft\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acesso ao prontu\u00e1rio do paciente - Blog ProDoctor","description":"Como \u00e9 o acesso ao prontu\u00e1rio do paciente na sua cl\u00ednica ou consult\u00f3rio? Um documento t\u00e3o importante precisa de cuidados. Veja nossas dicas!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prodoctor.net\/blog\/acesso-ao-prontuario-do-paciente\/","og_locale":"pt_BR","og_type":"article","og_title":"Acesso ao prontu\u00e1rio do paciente - Blog ProDoctor","og_description":"Como \u00e9 o acesso ao prontu\u00e1rio do paciente na sua cl\u00ednica ou consult\u00f3rio? Um documento t\u00e3o importante precisa de cuidados. Veja nossas dicas!","og_url":"https:\/\/prodoctor.net\/blog\/acesso-ao-prontuario-do-paciente\/","og_site_name":"Blog ProDoctor","article_publisher":"https:\/\/www.facebook.com\/prodoctorsoftware","article_published_time":"2021-03-15T17:53:33+00:00","article_modified_time":"2024-02-28T19:19:33+00:00","og_image":[{"width":770,"height":400,"url":"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2021\/03\/legislacao.jpg","type":"image\/jpeg"}],"author":"ProDoctor Software","twitter_card":"summary_large_image","twitter_creator":"@prodoctorsoft","twitter_site":"@prodoctorsoft","twitter_misc":{"Escrito por":"ProDoctor Software","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prodoctor.net\/blog\/acesso-ao-prontuario-do-paciente\/#article","isPartOf":{"@id":"https:\/\/prodoctor.net\/blog\/acesso-ao-prontuario-do-paciente\/"},"author":{"name":"ProDoctor Software","@id":"https:\/\/prodoctor.net\/blog\/#\/schema\/person\/8878914b17cd360e7ec0ddee1ed8c544"},"headline":"Acesso ao prontu\u00e1rio do paciente","datePublished":"2021-03-15T17:53:33+00:00","dateModified":"2024-02-28T19:19:33+00:00","mainEntityOfPage":{"@id":"https:\/\/prodoctor.net\/blog\/acesso-ao-prontuario-do-paciente\/"},"wordCount":698,"publisher":{"@id":"https:\/\/prodoctor.net\/blog\/#organization"},"image":{"@id":"https:\/\/prodoctor.net\/blog\/acesso-ao-prontuario-do-paciente\/#primaryimage"},"thumbnailUrl":"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2021\/03\/legislacao.jpg","articleSection":["Gest\u00e3o de Cl\u00ednicas e Consult\u00f3rios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/prodoctor.net\/blog\/acesso-ao-prontuario-do-paciente\/","url":"https:\/\/prodoctor.net\/blog\/acesso-ao-prontuario-do-paciente\/","name":"Acesso ao prontu\u00e1rio do paciente - Blog ProDoctor","isPartOf":{"@id":"https:\/\/prodoctor.net\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prodoctor.net\/blog\/acesso-ao-prontuario-do-paciente\/#primaryimage"},"image":{"@id":"https:\/\/prodoctor.net\/blog\/acesso-ao-prontuario-do-paciente\/#primaryimage"},"thumbnailUrl":"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2021\/03\/legislacao.jpg","datePublished":"2021-03-15T17:53:33+00:00","dateModified":"2024-02-28T19:19:33+00:00","description":"Como \u00e9 o acesso ao prontu\u00e1rio do paciente na sua cl\u00ednica ou consult\u00f3rio? Um documento t\u00e3o importante precisa de cuidados. Veja nossas dicas!","breadcrumb":{"@id":"https:\/\/prodoctor.net\/blog\/acesso-ao-prontuario-do-paciente\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prodoctor.net\/blog\/acesso-ao-prontuario-do-paciente\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/prodoctor.net\/blog\/acesso-ao-prontuario-do-paciente\/#primaryimage","url":"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2021\/03\/legislacao.jpg","contentUrl":"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2021\/03\/legislacao.jpg","width":770,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/prodoctor.net\/blog\/acesso-ao-prontuario-do-paciente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/prodoctor.net\/blog\/"},{"@type":"ListItem","position":2,"name":"Acesso ao prontu\u00e1rio do paciente"}]},{"@type":"WebSite","@id":"https:\/\/prodoctor.net\/blog\/#website","url":"https:\/\/prodoctor.net\/blog\/","name":"Blog ProDoctor","description":"Tudo sobre o mundo da Sa\u00fade","publisher":{"@id":"https:\/\/prodoctor.net\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prodoctor.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/prodoctor.net\/blog\/#organization","name":"ProDoctor Software S\/A","url":"https:\/\/prodoctor.net\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/prodoctor.net\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2017\/01\/Logo_PDo_Lateral.png","contentUrl":"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2017\/01\/Logo_PDo_Lateral.png","width":2014,"height":485,"caption":"ProDoctor Software S\/A"},"image":{"@id":"https:\/\/prodoctor.net\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prodoctorsoftware","https:\/\/x.com\/prodoctorsoft","https:\/\/www.instagram.com\/prodoctorsoftware\/","https:\/\/www.linkedin.com\/company\/prodoctor-software-ltda","https:\/\/www.youtube.com\/channel\/UCIWuDLsVtIpX-PEqQn1pNlw"]},{"@type":"Person","@id":"https:\/\/prodoctor.net\/blog\/#\/schema\/person\/8878914b17cd360e7ec0ddee1ed8c544","name":"ProDoctor Software","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/prodoctor.net\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a67bdb10f2e6695f7ae356a84deeaf10b545567f0ac054e9bfe8ec56e86317ec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a67bdb10f2e6695f7ae356a84deeaf10b545567f0ac054e9bfe8ec56e86317ec?s=96&d=mm&r=g","caption":"ProDoctor Software"},"sameAs":["http:\/\/prodoctor.net","https:\/\/x.com\/prodoctorsoft"]}]}},"taxonomy_info":{"category":[{"value":412,"label":"Gest\u00e3o de Cl\u00ednicas e Consult\u00f3rios"}]},"featured_image_src_large":["https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2021\/03\/legislacao.jpg",770,400,false],"author_info":{"display_name":"ProDoctor Software","author_link":"https:\/\/prodoctor.net\/blog\/author\/redesocialprodoctor-net\/"},"comment_info":0,"category_info":[{"term_id":412,"name":"Gest\u00e3o de Cl\u00ednicas e Consult\u00f3rios","slug":"gestao-de-clinicas-e-consultorios","term_group":0,"term_taxonomy_id":412,"taxonomy":"category","description":"","parent":0,"count":293,"filter":"raw","cat_ID":412,"category_count":293,"category_description":"","cat_name":"Gest\u00e3o de Cl\u00ednicas e Consult\u00f3rios","category_nicename":"gestao-de-clinicas-e-consultorios","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/posts\/18587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/comments?post=18587"}],"version-history":[{"count":7,"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/posts\/18587\/revisions"}],"predecessor-version":[{"id":28314,"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/posts\/18587\/revisions\/28314"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/media\/18606"}],"wp:attachment":[{"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/media?parent=18587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/categories?post=18587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/tags?post=18587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}