{"id":13122,"date":"2019-08-22T13:02:04","date_gmt":"2019-08-22T16:02:04","guid":{"rendered":"https:\/\/prodoctor.net\/blog\/?p=13122"},"modified":"2024-03-25T09:56:17","modified_gmt":"2024-03-25T12:56:17","slug":"canvas-para-clinica-tudo-o-que-voce-precisa-saber","status":"publish","type":"post","link":"https:\/\/prodoctor.net\/blog\/canvas-para-clinica-tudo-o-que-voce-precisa-saber\/","title":{"rendered":"Canvas para cl\u00ednica: tudo o que voc\u00ea precisa saber"},"content":{"rendered":"\n<p>Talvez voc\u00ea j\u00e1 tenha ouvido falar, mas \u00e9 prov\u00e1vel que ainda n\u00e3o saiba de fato o que \u00e9 o <strong>m\u00e9todo Canvas para cl\u00ednicas m\u00e9dicas<\/strong>. Durante sua forma\u00e7\u00e3o acad\u00eamica, com toda a certeza, n\u00e3o teve aulas e nem tempo para saber mais sobre<a rel=\"noreferrer noopener\" aria-label=\" empreendedorismo (opens in a new tab)\" href=\"https:\/\/prodoctor.net\/blog\/gestao-de-consultorios-tudo-o-que-voce-precisa-saber\/\" target=\"_blank\"> empreendedorismo<\/a>. Todavia, agora que tem o seu pr\u00f3prio neg\u00f3cio, \u00e9 importante  n\u00e3o apenas conhecer, mas tamb\u00e9m aplicar o <strong>Business Model Canvas<\/strong>.<\/p>\n\n\n\n<p>Seu trabalho \u00e9 uma <strong>luta di\u00e1ria contra o tempo<\/strong>. Por isso, com o prop\u00f3sito de ajud\u00e1-lo a entender melhor o m\u00e9todo, elaboramos este post. Assim, al\u00e9m de tirar d\u00favidas, poder\u00e1 elaborar <strong>novos planos<\/strong> para o crescimento da empresa.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<p><strong>Aqui voc\u00ea encontrar\u00e1 abordagens sobre:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Software de gest\u00e3o;<\/li>\n\n\n\n<li>Networking;<\/li>\n\n\n\n<li>O que \u00e9 o m\u00e9todo Canvas;<\/li>\n\n\n\n<li>Como utilizar o Canvas em Cl\u00ednicas M\u00e9dicas;<\/li>\n\n\n\n<li>A import\u00e2ncia de ter um software de gest\u00e3o. <\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">A import\u00e2ncia de ter um software de gest\u00e3o<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"770\" height=\"250\" src=\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2019\/08\/a-importancia-em-ter-um-software-de-gestao.jpg\" alt=\"A importa^ncia de ter um software de gest\u00e3o\" class=\"wp-image-13309\" srcset=\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2019\/08\/a-importancia-em-ter-um-software-de-gestao.jpg 770w, https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2019\/08\/a-importancia-em-ter-um-software-de-gestao-300x97.jpg 300w, https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2019\/08\/a-importancia-em-ter-um-software-de-gestao-768x249.jpg 768w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/figure>\n\n\n\n<p>Se acaso voc\u00ea quer ver o crescimento de sua cl\u00ednica, com toda a certeza n\u00e3o poder\u00e1 abrir m\u00e3o de usar um <a rel=\"noreferrer noopener\" aria-label=\"software de gest\u00e3o (opens in a new tab)\" href=\"https:\/\/prodoctor.net\/\" target=\"_blank\">software de gest\u00e3o<\/a>. Sem d\u00favida, a Tecnologia da Informa\u00e7\u00e3o \u00e9 um <strong>importante aliado<\/strong> para enfrentar uma concorr\u00eancia cada vez mais acirrada.<\/p>\n\n\n\n<p> Com um software de gest\u00e3o, voc\u00ea n\u00e3o s\u00f3 reduzir\u00e1 os custos da cl\u00ednica, bem como melhorar a qualidade do atendimento. Al\u00e9m disso, tamb\u00e9m<strong> aumentar\u00e1 os lucros da empresa<\/strong>. Para que isto se concretize, veja os recursos tecnol\u00f3gicos dispon\u00edveis, a fim de viabilizar as a\u00e7\u00f5es e concretizar as metas. Entretanto, esteja alerta e<a href=\"https:\/\/prodoctor.net\/blog\/10-coisas-que-um-bom-software-de-gestao-precisa-ter\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" escolha um software de gest\u00e3o confi\u00e1vel, (opens in a new tab)\"> escolha um software de gest\u00e3o confi\u00e1vel,<\/a> uma vez que esta ferramenta ser\u00e1 fundamental para consolidar o processo. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Por que ter uma rede de relacionamentos?<\/h2>\n\n\n\n<p>Al\u00e9m dos seus conhecimentos cient\u00edficos e habilidades necess\u00e1rias para exercer a Medicina, tamb\u00e9m \u00e9 importante que voc\u00ea se mantenha atualizado, a fim de enfrentar a concorr\u00eancia<strong> <\/strong>e se tornar refer\u00eancia em sua especialidade.<\/p>\n\n\n\n<p>Portanto, esteja sempre em<strong> contato com outros m\u00e9dicos<\/strong>. Al\u00e9m disso, \u00e9 importante<strong> <\/strong><a href=\"https:\/\/prodoctor.net\/blog\/prodoctor-software-10-anos-consecutivos-na-feira-hospitalar\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"participar de congressos, semin\u00e1rios e eventos de sua \u00e1rea (opens in a new tab)\">participar de congressos, semin\u00e1rios e eventos de sua \u00e1rea<\/a>. Dessa maneira, aumentar\u00e1 o raio de a\u00e7\u00e3o sobre o qual pode interagir.<\/p>\n\n\n\n<p>Ao mesmo tempo, estabelecer\u00e1 uma rede de informa\u00e7\u00e3o e trabalho. Como resultado, poder\u00e1 n\u00e3o apenas disponibilizar sua imagem profissional, mas tamb\u00e9m <strong>disseminar os benef\u00edcios<\/strong> que os pacientes ter\u00e3o ao escolher sua cl\u00ednica.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O m\u00e9todo Canvas para cl\u00ednica<\/h2>\n\n\n\n<p>Este modelo de planejamento estrat\u00e9gico foi criado pelo pesquisador su\u00ed\u00e7o <a href=\"https:\/\/en.wikipedia.org\/wiki\/Alexander_Osterwalder\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Alexander Osterwalder (opens in a new tab)\">Alexander Osterwalder<\/a>, que dedicou grande parte da vida trabalhando em m\u00e9todos de empreendedorismo. Al\u00e9m de ter uma \u00f3tima ideia, ele sabia que para torn\u00e1-la uma realidade e um neg\u00f3cio rent\u00e1vel, \u00e9 necess\u00e1rio seguir \u00e0 risca esta ferramenta.<\/p>\n\n\n\n<p>Com a utiliza\u00e7\u00e3o do Canvas, o empreendedor consegue entender seus <strong>pontos fortes e fracos<\/strong>. Assim, \u00e9 poss\u00edvel saber, de fato, onde atuar para alcan\u00e7ar as melhorias.<\/p>\n\n\n\n<p>O Sebrae desenvolveu uma ferramenta online para ajudar voc\u00ea a moldar o seu neg\u00f3cio com o Canvas.  Para acessar, clique <a href=\"https:\/\/www.sebraecanvas.com\/#\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"aqui (opens in a new tab)\">aqui<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O m\u00e9todo Canvas para cl\u00ednica m\u00e9dica<\/h2>\n\n\n\n<p>O m\u00e9todo Canvas para cl\u00ednicas m\u00e9dicas n\u00e3o \u00e9 um mero plano de neg\u00f3cios que, pelos seus detalhes, demandaria muito mais tempo para ser implementado. Por outro lado, pelo seu dinamismo, ele apresenta <strong>facilidade de compreens\u00e3o e de execu\u00e7\u00e3o<\/strong>.<\/p>\n\n\n\n<p>Antes de mais nada, na <strong>Proposta de valor<\/strong>, defina o diferencial de sua cl\u00ednica m\u00e9dica, a fim de ressaltar os seus pontos fortes. Desse modo, os pacientes criar\u00e3o em seu imagin\u00e1rio uma expectativa bastante favor\u00e1vel sobre a cl\u00ednica.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cadastro de clientes<\/h2>\n\n\n\n<p>Em seguida, cadastre os pacientes que formar\u00e3o o seu <strong>Segmento de clientes<\/strong>. Mantenha atualizado o cadastro do seu p\u00fablico-alvo. Al\u00e9m disso, procure conhecer e cativar cada um deles. N\u00e3o basta apenas preencher o nome do paciente, mas tamb\u00e9m ter em m\u00e3os dados capazes de facilitar e agilizar o p\u00f3s-atendimento.<\/p>\n\n\n\n<p>Nesse\nsentido, \u00e9 importante ter cadastrados dados como, por exemplo, faixa\net\u00e1ria, classe econ\u00f4mica e a idade, dentre outros.<\/p>\n\n\n\n<p>Em resumo, voc\u00ea precisa definir estrat\u00e9gias para n\u00e3o s\u00f3 atrair, mas tamb\u00e9m <strong>converter e fidelizar<\/strong> seus pacientes\/clientes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Como divulgar sua cl\u00ednica?<\/strong><\/h2>\n\n\n\n<p>Posteriormente, analise com aten\u00e7\u00e3o a forma que utilizar\u00e1 para alcan\u00e7ar seus pacientes. Assim que mapear onde se encontram, escolha a melhor op\u00e7\u00e3o. Por exemplo: via redes sociais, por e-mail ou telefone. Al\u00e9m de optar pelo melhor caminho, n\u00e3o se esque\u00e7a de estudar os custos da opera\u00e7\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Com o olho nas finan\u00e7as<\/h2>\n\n\n\n<p>O <strong>m\u00e9todo Canvas para cl\u00ednicas m\u00e9dicas<\/strong> proporciona um cuidado especial com os neg\u00f3cios. Nesse sentido, voc\u00ea precisa definir como sua cl\u00ednica ter\u00e1 entradas financeiras. Primeiramente, estude a possibilidade de alugar uma ou mais salas para outros profissionais.<\/p>\n\n\n\n<p>De acordo com o que decidir, ent\u00e3o, saber\u00e1 de onde sair\u00e3o seus rendimentos. Se acaso n\u00e3o alugar, poder\u00e1 contar apenas com o seu trabalho, recebendo tanto pelas consultas quanto pelos procedimentos e\/ou cirurgias.<\/p>\n\n\n\n<p>Tenha sempre em mente: a cl\u00ednica m\u00e9dica \u00e9 um <strong>neg\u00f3cio como outro qualquer<\/strong>. Portanto, precisa sobreviver no mercado. Por isso, precisa gerar receita. No momento em que seus passos s\u00e3o validados, voc\u00ea caminha para se sustentar. Assim, suas propostas tornam-se vi\u00e1veis.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Fontes de recursos<\/h2>\n\n\n\n<p>A fim de que o processo seja iniciado, \u00e9 importante listar e verificar tudo o que \u00e9 necess\u00e1rio para a cl\u00ednica funcionar. Dessa forma, <strong>fa\u00e7a um mapa abrangendo todas as salas<\/strong>, com todos os equipamentos que ser\u00e3o utilizados, n\u00e3o apenas por voc\u00ea, mas tamb\u00e9m pela secret\u00e1ria e demais colaboradores. Ao mesmo tempo, liste desde materiais, como por exemplo papeis, at\u00e9 o uso da energia el\u00e9trica. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Procedimentos da cl\u00ednica<\/h2>\n\n\n\n<p>De maneira id\u00eantica, <strong>fa\u00e7a uma lista <\/strong>a fim de mostrar detalhadamente como prestar\u00e1 seus servi\u00e7os. Por exemplo: explique a forma como realizar\u00e1 cada procedimento, bem como <strong>identifique as salas dispon\u00edveis<\/strong> para atender os pacientes com os seus respectivos equipamentos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">A import\u00e2ncia das parcerias<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2017\/08\/Motivos-para-adotar-a-tecnologia-na-gestao-de-consultorios.png\"><img decoding=\"async\" width=\"770\" height=\"250\" src=\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2017\/08\/Motivos-para-adotar-a-tecnologia-na-gestao-de-consultorios.png\" alt=\"A import\u00e2ncia das parcerias\" class=\"wp-image-19991\" srcset=\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2017\/08\/Motivos-para-adotar-a-tecnologia-na-gestao-de-consultorios.png 770w, https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2017\/08\/Motivos-para-adotar-a-tecnologia-na-gestao-de-consultorios-300x97.png 300w, https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2017\/08\/Motivos-para-adotar-a-tecnologia-na-gestao-de-consultorios-768x249.png 768w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/a><\/figure>\n\n\n\n<p>\u00c9 importante estabelecer parcerias, que de tal forma podem ajud\u00e1-lo na abertura do neg\u00f3cio. Fa\u00e7a uma <strong>rela\u00e7\u00e3o com nomes de pessoas e empresas<\/strong>, pois dessa forma visualizar\u00e1 melhor as atividades em que se encaixam para entregar sua proposta de valor.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Gest\u00e3o de custo<\/h2>\n\n\n\n<p>Os gastos de sua cl\u00ednica devem ser <strong>gerenciados racionalmente<\/strong>. Ou seja, com a utiliza\u00e7\u00e3o inteligente dos recursos. Assim, ser\u00e1 poss\u00edvel identificar oportunidades para <strong>investir e aumentar os lucros<\/strong> da cl\u00ednica.  Para que isto aconte\u00e7a, primeiramente, fa\u00e7a uma lista com todos os gastos, como por exemplo, materiais, contas mensais, m\u00e3o de obra, impostos e  aluguel, dentre outros.<\/p>\n\n\n\n<p>Ao mesmo tempo, relacione todas as atividades relevantes para o bom funcionamento do empreendimento. Assim, saber\u00e1 quanto est\u00e1 gastando para conseguir manter o neg\u00f3cio. De fato, \u00e9 importante entender os princ\u00edpios de uma<a href=\"https:\/\/prodoctor.net\/blog\/gestao-de-clinicas-o-guia-definitivo\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" boa&nbsp;gest\u00e3o (opens in a new tab)\"> boa&nbsp;gest\u00e3o<\/a> de custos, uma vez que ter\u00e1 influ\u00eancia direta na sua margem de lucro.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conclus\u00e3o<\/h2>\n\n\n\n<p class=\"western\">Com toda a certeza, agora voc\u00ea disp\u00f5e agora de excelentes informa\u00e7\u00f5es sobre o m\u00e9todo Canvas para cl\u00ednicas. Depois que suas d\u00favidas foram esclarecidas, o importante \u00e9 estar atento ao <strong>acompanhamento de sua estrat\u00e9gia<\/strong>, a fim de conferir as a\u00e7\u00f5es. Assim, poder\u00e1 conferir os acertos e corrigir poss\u00edveis erros.<\/p>\n\n\n\n<div class=\"wp-block-cover paralax-pequeno\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\"><\/span><img decoding=\"async\" width=\"842\" height=\"595\" class=\"wp-block-cover__image-background wp-image-12744\" alt=\"\" src=\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2019\/07\/e-book-10-erros-mais-comuns-ao-abrir-seu-consultorio-e-como-evita-los.jpg\" style=\"object-position:17% 24%\" data-object-fit=\"cover\" data-object-position=\"17% 24%\" srcset=\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2019\/07\/e-book-10-erros-mais-comuns-ao-abrir-seu-consultorio-e-como-evita-los.jpg 842w, https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2019\/07\/e-book-10-erros-mais-comuns-ao-abrir-seu-consultorio-e-como-evita-los-300x212.jpg 300w, https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2019\/07\/e-book-10-erros-mais-comuns-ao-abrir-seu-consultorio-e-como-evita-los-768x543.jpg 768w\" sizes=\"(max-width: 842px) 100vw, 842px\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<p class=\"has-text-align-center has-very-light-gray-color has-text-color has-large-font-size\">Saiba os erros mais comuns em abrir seu consult\u00f3rio e evite-os<\/p>\n\n\n\n<p class=\"has-very-light-gray-color has-text-color\"><span class=\"tadv-color\" style=\"color:#eeeeee\">Um apanhado com dicas para te ajudar na hora de abrir seu consult\u00f3rio!\u00a0<\/span><strong><span class=\"tadv-color\" style=\"color:#eeeeee\">Neste e-book voc\u00ea ir\u00e1 encontrar:<\/span><\/strong><span class=\"tadv-color\" style=\"color:#eeeeee\"> Localiza\u00e7\u00e3o, Documenta\u00e7\u00e3o, Custos de abertura e funcionamento, entre outros. <\/span><\/p>\n\n\n\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"https:\/\/mkt.prodoctor.net\/10-erros-mais-comuns-ao-abrir-seu-consultorio-e-como-evita-los\" style=\"background-color:#ff5722\" target=\"_blank\" rel=\"noreferrer noopener\">Baixar Material Gratuito<\/a><\/div>\n<\/div><\/div>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Talvez voc\u00ea j\u00e1 tenha ouvido falar, mas \u00e9 prov\u00e1vel que ainda n\u00e3o saiba de fato o que \u00e9 o m\u00e9todo Canvas para cl\u00ednicas m\u00e9dicas. Durante sua forma\u00e7\u00e3o acad\u00eamica, com toda a certeza, n\u00e3o teve aulas e nem tempo para saber mais sobre empreendedorismo. Todavia, agora que tem o seu pr\u00f3prio neg\u00f3cio, \u00e9 importante  n\u00e3o apenas conhecer, mas tamb\u00e9m aplicar o Business Model Canvas.<\/p>\n","protected":false},"author":1,"featured_media":20141,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[412],"tags":[459,460,444,438,404,405,439],"class_list":["post-13122","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gestao-de-clinicas-e-consultorios","tag-canvas","tag-canvas-para-clinicas","tag-gestao-de-clinicas","tag-prodoctor-cloud","tag-prodoctor-corp","tag-prodoctor-plus","tag-prodoctor-software"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Canvas para Cl\u00ednica M\u00e9dica - Blog ProDoctor<\/title>\n<meta name=\"description\" content=\"As Canvas para cl\u00ednica podem ter muitas funcionalidades na gest\u00e3o. Saiba como usar a ferramenta para entender seu neg\u00f3cio, seus pontos fortes e fracos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prodoctor.net\/blog\/canvas-para-clinica-tudo-o-que-voce-precisa-saber\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Canvas para Cl\u00ednica M\u00e9dica - Blog ProDoctor\" \/>\n<meta property=\"og:description\" content=\"As Canvas para cl\u00ednica podem ter muitas funcionalidades na gest\u00e3o. Saiba como usar a ferramenta para entender seu neg\u00f3cio, seus pontos fortes e fracos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prodoctor.net\/blog\/canvas-para-clinica-tudo-o-que-voce-precisa-saber\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog ProDoctor\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prodoctorsoftware\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-22T16:02:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-25T12:56:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2018\/05\/Software-medico-Como-utilizar-o-computador-durante-a-consulta.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"770\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ProDoctor Software\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@prodoctorsoft\" \/>\n<meta name=\"twitter:site\" content=\"@prodoctorsoft\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ProDoctor Software\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/prodoctor.net\/blog\/canvas-para-clinica-tudo-o-que-voce-precisa-saber\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/canvas-para-clinica-tudo-o-que-voce-precisa-saber\/\"},\"author\":{\"name\":\"ProDoctor Software\",\"@id\":\"https:\/\/prodoctor.net\/blog\/#\/schema\/person\/8878914b17cd360e7ec0ddee1ed8c544\"},\"headline\":\"Canvas para cl\u00ednica: tudo o que voc\u00ea precisa saber\",\"datePublished\":\"2019-08-22T16:02:04+00:00\",\"dateModified\":\"2024-03-25T12:56:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/canvas-para-clinica-tudo-o-que-voce-precisa-saber\/\"},\"wordCount\":1301,\"publisher\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/canvas-para-clinica-tudo-o-que-voce-precisa-saber\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2018\/05\/Software-medico-Como-utilizar-o-computador-durante-a-consulta.jpg\",\"keywords\":[\"Canvas\",\"Canvas para cl\u00ednicas\",\"gest\u00e3o de cl\u00ednicas\",\"ProDoctor Cloud\",\"ProDoctor Corp\",\"ProDoctor Plus\",\"ProDoctor Software\"],\"articleSection\":[\"Gest\u00e3o de Cl\u00ednicas e Consult\u00f3rios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/prodoctor.net\/blog\/canvas-para-clinica-tudo-o-que-voce-precisa-saber\/\",\"url\":\"https:\/\/prodoctor.net\/blog\/canvas-para-clinica-tudo-o-que-voce-precisa-saber\/\",\"name\":\"Canvas para Cl\u00ednica M\u00e9dica - Blog ProDoctor\",\"isPartOf\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/canvas-para-clinica-tudo-o-que-voce-precisa-saber\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/canvas-para-clinica-tudo-o-que-voce-precisa-saber\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2018\/05\/Software-medico-Como-utilizar-o-computador-durante-a-consulta.jpg\",\"datePublished\":\"2019-08-22T16:02:04+00:00\",\"dateModified\":\"2024-03-25T12:56:17+00:00\",\"description\":\"As Canvas para cl\u00ednica podem ter muitas funcionalidades na gest\u00e3o. Saiba como usar a ferramenta para entender seu neg\u00f3cio, seus pontos fortes e fracos.\",\"breadcrumb\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/canvas-para-clinica-tudo-o-que-voce-precisa-saber\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/prodoctor.net\/blog\/canvas-para-clinica-tudo-o-que-voce-precisa-saber\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/prodoctor.net\/blog\/canvas-para-clinica-tudo-o-que-voce-precisa-saber\/#primaryimage\",\"url\":\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2018\/05\/Software-medico-Como-utilizar-o-computador-durante-a-consulta.jpg\",\"contentUrl\":\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2018\/05\/Software-medico-Como-utilizar-o-computador-durante-a-consulta.jpg\",\"width\":770,\"height\":400,\"caption\":\"Canvas para cl\u00ednicas m\u00e9dicas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/prodoctor.net\/blog\/canvas-para-clinica-tudo-o-que-voce-precisa-saber\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/prodoctor.net\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Canvas para cl\u00ednica: tudo o que voc\u00ea precisa saber\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/prodoctor.net\/blog\/#website\",\"url\":\"https:\/\/prodoctor.net\/blog\/\",\"name\":\"Blog ProDoctor\",\"description\":\"Tudo sobre o mundo da Sa\u00fade\",\"publisher\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/prodoctor.net\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/prodoctor.net\/blog\/#organization\",\"name\":\"ProDoctor Software S\/A\",\"url\":\"https:\/\/prodoctor.net\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/prodoctor.net\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2017\/01\/Logo_PDo_Lateral.png\",\"contentUrl\":\"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2017\/01\/Logo_PDo_Lateral.png\",\"width\":2014,\"height\":485,\"caption\":\"ProDoctor Software S\/A\"},\"image\":{\"@id\":\"https:\/\/prodoctor.net\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/prodoctorsoftware\",\"https:\/\/x.com\/prodoctorsoft\",\"https:\/\/www.instagram.com\/prodoctorsoftware\/\",\"https:\/\/www.linkedin.com\/company\/prodoctor-software-ltda\",\"https:\/\/www.youtube.com\/channel\/UCIWuDLsVtIpX-PEqQn1pNlw\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/prodoctor.net\/blog\/#\/schema\/person\/8878914b17cd360e7ec0ddee1ed8c544\",\"name\":\"ProDoctor Software\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/prodoctor.net\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a67bdb10f2e6695f7ae356a84deeaf10b545567f0ac054e9bfe8ec56e86317ec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a67bdb10f2e6695f7ae356a84deeaf10b545567f0ac054e9bfe8ec56e86317ec?s=96&d=mm&r=g\",\"caption\":\"ProDoctor Software\"},\"sameAs\":[\"http:\/\/prodoctor.net\",\"https:\/\/x.com\/prodoctorsoft\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Canvas para Cl\u00ednica M\u00e9dica - Blog ProDoctor","description":"As Canvas para cl\u00ednica podem ter muitas funcionalidades na gest\u00e3o. Saiba como usar a ferramenta para entender seu neg\u00f3cio, seus pontos fortes e fracos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prodoctor.net\/blog\/canvas-para-clinica-tudo-o-que-voce-precisa-saber\/","og_locale":"pt_BR","og_type":"article","og_title":"Canvas para Cl\u00ednica M\u00e9dica - Blog ProDoctor","og_description":"As Canvas para cl\u00ednica podem ter muitas funcionalidades na gest\u00e3o. Saiba como usar a ferramenta para entender seu neg\u00f3cio, seus pontos fortes e fracos.","og_url":"https:\/\/prodoctor.net\/blog\/canvas-para-clinica-tudo-o-que-voce-precisa-saber\/","og_site_name":"Blog ProDoctor","article_publisher":"https:\/\/www.facebook.com\/prodoctorsoftware","article_published_time":"2019-08-22T16:02:04+00:00","article_modified_time":"2024-03-25T12:56:17+00:00","og_image":[{"width":770,"height":400,"url":"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2018\/05\/Software-medico-Como-utilizar-o-computador-durante-a-consulta.jpg","type":"image\/jpeg"}],"author":"ProDoctor Software","twitter_card":"summary_large_image","twitter_creator":"@prodoctorsoft","twitter_site":"@prodoctorsoft","twitter_misc":{"Escrito por":"ProDoctor Software","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prodoctor.net\/blog\/canvas-para-clinica-tudo-o-que-voce-precisa-saber\/#article","isPartOf":{"@id":"https:\/\/prodoctor.net\/blog\/canvas-para-clinica-tudo-o-que-voce-precisa-saber\/"},"author":{"name":"ProDoctor Software","@id":"https:\/\/prodoctor.net\/blog\/#\/schema\/person\/8878914b17cd360e7ec0ddee1ed8c544"},"headline":"Canvas para cl\u00ednica: tudo o que voc\u00ea precisa saber","datePublished":"2019-08-22T16:02:04+00:00","dateModified":"2024-03-25T12:56:17+00:00","mainEntityOfPage":{"@id":"https:\/\/prodoctor.net\/blog\/canvas-para-clinica-tudo-o-que-voce-precisa-saber\/"},"wordCount":1301,"publisher":{"@id":"https:\/\/prodoctor.net\/blog\/#organization"},"image":{"@id":"https:\/\/prodoctor.net\/blog\/canvas-para-clinica-tudo-o-que-voce-precisa-saber\/#primaryimage"},"thumbnailUrl":"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2018\/05\/Software-medico-Como-utilizar-o-computador-durante-a-consulta.jpg","keywords":["Canvas","Canvas para cl\u00ednicas","gest\u00e3o de cl\u00ednicas","ProDoctor Cloud","ProDoctor Corp","ProDoctor Plus","ProDoctor Software"],"articleSection":["Gest\u00e3o de Cl\u00ednicas e Consult\u00f3rios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/prodoctor.net\/blog\/canvas-para-clinica-tudo-o-que-voce-precisa-saber\/","url":"https:\/\/prodoctor.net\/blog\/canvas-para-clinica-tudo-o-que-voce-precisa-saber\/","name":"Canvas para Cl\u00ednica M\u00e9dica - Blog ProDoctor","isPartOf":{"@id":"https:\/\/prodoctor.net\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prodoctor.net\/blog\/canvas-para-clinica-tudo-o-que-voce-precisa-saber\/#primaryimage"},"image":{"@id":"https:\/\/prodoctor.net\/blog\/canvas-para-clinica-tudo-o-que-voce-precisa-saber\/#primaryimage"},"thumbnailUrl":"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2018\/05\/Software-medico-Como-utilizar-o-computador-durante-a-consulta.jpg","datePublished":"2019-08-22T16:02:04+00:00","dateModified":"2024-03-25T12:56:17+00:00","description":"As Canvas para cl\u00ednica podem ter muitas funcionalidades na gest\u00e3o. Saiba como usar a ferramenta para entender seu neg\u00f3cio, seus pontos fortes e fracos.","breadcrumb":{"@id":"https:\/\/prodoctor.net\/blog\/canvas-para-clinica-tudo-o-que-voce-precisa-saber\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prodoctor.net\/blog\/canvas-para-clinica-tudo-o-que-voce-precisa-saber\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/prodoctor.net\/blog\/canvas-para-clinica-tudo-o-que-voce-precisa-saber\/#primaryimage","url":"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2018\/05\/Software-medico-Como-utilizar-o-computador-durante-a-consulta.jpg","contentUrl":"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2018\/05\/Software-medico-Como-utilizar-o-computador-durante-a-consulta.jpg","width":770,"height":400,"caption":"Canvas para cl\u00ednicas m\u00e9dicas"},{"@type":"BreadcrumbList","@id":"https:\/\/prodoctor.net\/blog\/canvas-para-clinica-tudo-o-que-voce-precisa-saber\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/prodoctor.net\/blog\/"},{"@type":"ListItem","position":2,"name":"Canvas para cl\u00ednica: tudo o que voc\u00ea precisa saber"}]},{"@type":"WebSite","@id":"https:\/\/prodoctor.net\/blog\/#website","url":"https:\/\/prodoctor.net\/blog\/","name":"Blog ProDoctor","description":"Tudo sobre o mundo da Sa\u00fade","publisher":{"@id":"https:\/\/prodoctor.net\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prodoctor.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/prodoctor.net\/blog\/#organization","name":"ProDoctor Software S\/A","url":"https:\/\/prodoctor.net\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/prodoctor.net\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2017\/01\/Logo_PDo_Lateral.png","contentUrl":"https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2017\/01\/Logo_PDo_Lateral.png","width":2014,"height":485,"caption":"ProDoctor Software S\/A"},"image":{"@id":"https:\/\/prodoctor.net\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prodoctorsoftware","https:\/\/x.com\/prodoctorsoft","https:\/\/www.instagram.com\/prodoctorsoftware\/","https:\/\/www.linkedin.com\/company\/prodoctor-software-ltda","https:\/\/www.youtube.com\/channel\/UCIWuDLsVtIpX-PEqQn1pNlw"]},{"@type":"Person","@id":"https:\/\/prodoctor.net\/blog\/#\/schema\/person\/8878914b17cd360e7ec0ddee1ed8c544","name":"ProDoctor Software","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/prodoctor.net\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a67bdb10f2e6695f7ae356a84deeaf10b545567f0ac054e9bfe8ec56e86317ec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a67bdb10f2e6695f7ae356a84deeaf10b545567f0ac054e9bfe8ec56e86317ec?s=96&d=mm&r=g","caption":"ProDoctor Software"},"sameAs":["http:\/\/prodoctor.net","https:\/\/x.com\/prodoctorsoft"]}]}},"taxonomy_info":{"category":[{"value":412,"label":"Gest\u00e3o de Cl\u00ednicas e Consult\u00f3rios"}],"post_tag":[{"value":459,"label":"Canvas"},{"value":460,"label":"Canvas para cl\u00ednicas"},{"value":444,"label":"gest\u00e3o de cl\u00ednicas"},{"value":438,"label":"ProDoctor Cloud"},{"value":404,"label":"ProDoctor Corp"},{"value":405,"label":"ProDoctor Plus"},{"value":439,"label":"ProDoctor Software"}]},"featured_image_src_large":["https:\/\/prodoctor.net\/blog\/wp-content\/uploads\/2018\/05\/Software-medico-Como-utilizar-o-computador-durante-a-consulta.jpg",770,400,false],"author_info":{"display_name":"ProDoctor Software","author_link":"https:\/\/prodoctor.net\/blog\/author\/redesocialprodoctor-net\/"},"comment_info":0,"category_info":[{"term_id":412,"name":"Gest\u00e3o de Cl\u00ednicas e Consult\u00f3rios","slug":"gestao-de-clinicas-e-consultorios","term_group":0,"term_taxonomy_id":412,"taxonomy":"category","description":"","parent":0,"count":299,"filter":"raw","cat_ID":412,"category_count":299,"category_description":"","cat_name":"Gest\u00e3o de Cl\u00ednicas e Consult\u00f3rios","category_nicename":"gestao-de-clinicas-e-consultorios","category_parent":0}],"tag_info":[{"term_id":459,"name":"Canvas","slug":"canvas","term_group":0,"term_taxonomy_id":459,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw"},{"term_id":460,"name":"Canvas para cl\u00ednicas","slug":"canvas-para-clinicas","term_group":0,"term_taxonomy_id":460,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw"},{"term_id":444,"name":"gest\u00e3o de cl\u00ednicas","slug":"gestao-de-clinicas","term_group":0,"term_taxonomy_id":444,"taxonomy":"post_tag","description":"","parent":0,"count":23,"filter":"raw"},{"term_id":438,"name":"ProDoctor Cloud","slug":"prodoctor-cloud","term_group":0,"term_taxonomy_id":438,"taxonomy":"post_tag","description":"","parent":0,"count":12,"filter":"raw"},{"term_id":404,"name":"ProDoctor Corp","slug":"prodoctor-corp","term_group":0,"term_taxonomy_id":4,"taxonomy":"post_tag","description":"","parent":0,"count":40,"filter":"raw"},{"term_id":405,"name":"ProDoctor Plus","slug":"prodoctor-plus","term_group":0,"term_taxonomy_id":5,"taxonomy":"post_tag","description":"","parent":0,"count":32,"filter":"raw"},{"term_id":439,"name":"ProDoctor Software","slug":"prodoctor-software","term_group":0,"term_taxonomy_id":439,"taxonomy":"post_tag","description":"","parent":0,"count":17,"filter":"raw"}],"_links":{"self":[{"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/posts\/13122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/comments?post=13122"}],"version-history":[{"count":25,"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/posts\/13122\/revisions"}],"predecessor-version":[{"id":28783,"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/posts\/13122\/revisions\/28783"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/media\/20141"}],"wp:attachment":[{"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/media?parent=13122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/categories?post=13122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prodoctor.net\/blog\/wp-json\/wp\/v2\/tags?post=13122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}